{"id":2973,"date":"2015-06-25T18:11:00","date_gmt":"2015-06-25T18:11:00","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=2973"},"modified":"2024-10-08T09:10:48","modified_gmt":"2024-10-08T12:10:48","slug":"curso-de-inclusao-digital-atende-mais-80-idosos","status":"publish","type":"post","link":"https:\/\/www.apucarana.pr.gov.br\/site\/curso-de-inclusao-digital-atende-mais-80-idosos\/","title":{"rendered":"Curso de inclus\u00e3o digital atende mais 80 idosos"},"content":{"rendered":"<\/p>\n<p><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\">Uma semana depois de formar a primeira turma com 120 idosos, a prefeitura de Apucarana, atrav\u00e9s da secretaria da Assist\u00eancia Social, em parceria com o SESC, lan\u00e7ou hoje (25) a segunda etapa do curso gratuito de Inclus\u00e3o Digital para Terceira Idade, com 75 alunos.<\/span><\/p>\n<p><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\"><b><a href=\"http:\/\/apucarana.pr.gov.br\/radioapucarana\/?p=187\" target=\"_blank\" rel=\"noopener\">Click e ou\u00e7a esta mat\u00e9ria<\/a><\/b><br \/><\/span><\/p>\n<p>&ldquo;Com o prop\u00f3sito de formar mil alunos at\u00e9 o final do ano dentro do projeto municipal de Inclus\u00e3o Digital para Terceira Idade, estamos iniciando uma nova turma e daremos todo incentivo e apoio para que outras se formem. Agrade\u00e7o a parceria do SESC e a cada um que vai estudar. Obrigado por acreditar nesta ideia que abre a porta para um mundo diferente. Vamos entrar neste mundo digital maravilhoso&rdquo;, conclamou o prefeito Beto Preto.<\/p>\n<p>Com in\u00edcio das aulas previsto j\u00e1 para pr\u00f3xima semana, os 75 alunos do curso ser\u00e3o divididos em 5 turmas de 15, sendo uma exclusiva para internos do Asilo S\u00e3o Vicente de Paulo. &ldquo;Temos uma sala de terapia ocupacional que conta com um computador e internet. Acredito que vamos precisar de mais ap\u00f3s nosso grupo terminar o curso. Estamos abertos para doa\u00e7\u00f5es de computadores para suprir essa demanda de novos internautas&rdquo;, disse o presidente do Lar S\u00e3o Vicente de Paulo, C\u00e9zar Farin\u00e1cio.<\/p>\n<p>A gerente executiva do SESC Apucarana, Aline Gouveia, comemorou a parceria com a prefeitura neste projeto que visa acabar com o analfabetismo digital. &ldquo;Foi estabelecida uma parceria com o munic\u00edpio que temos a inten\u00e7\u00e3o de ampliar. Trata-se de uma iniciativa que traz autonomia aos idosos&rdquo;, declarou a gerente do SESC. <\/p>\n<p>O SESC, conforme explica Aline, conta com o espa\u00e7o conex\u00e3o, com computadores de \u00faltima gera\u00e7\u00e3o, onde j\u00e1 oferece, dentro da sua programa\u00e7\u00e3o regular de atividades, o curso &ldquo;Melhor Click, com aulas de inform\u00e1tica para a terceira idade. <\/p>\n<p>A secret\u00e1ria da Assist\u00eancia Social, M\u00e1rcia Regina Sousa, lembrou, durante a solenidade de assinatura do conv\u00eanio entre a prefeitura e o SESC, que desde 2013 a atual gest\u00e3o desenvolve um trabalho que visa levar mais possibilidades e mais oportunidades para terceira idade. &ldquo;Tudo que realizamos para voc\u00eas foi solicita\u00e7\u00e3o e teve a participa\u00e7\u00e3o dos idosos, atendendo suas necessidades. &Eacute; a realiza\u00e7\u00e3o de um sonho poder oferecer esse curso gratuito de inform\u00e1tica para internos de uma entidade, como o lar S\u00e3o Vicente&rdquo;, observou M\u00e1rcia.<\/p>\n<p>Outras informa\u00e7\u00f5es para se inscrever para novas turmas curso de Inclus\u00e3o Digital para Terceira Idade podem ser obtidas no Centro de Qualifica\u00e7\u00e3o Total pelo telefone 3426-7241.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aulas de Introdu&ccedil;&atilde;o &agrave; Inform&aacute;tica com Internet come&ccedil;am na pr&oacute;xima semana numa parceria da prefeitura com o SESC<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2973","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=2973"}],"version-history":[{"count":1,"href":"https:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2973\/revisions"}],"predecessor-version":[{"id":103906,"href":"https:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2973\/revisions\/103906"}],"wp:attachment":[{"href":"https:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=2973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=2973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=2973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}