{"id":56312,"date":"2022-01-05T14:58:13","date_gmt":"2022-01-05T17:58:13","guid":{"rendered":"http:\/\/www.apucarana.pr.gov.br\/site\/?post_type=carta-de-servicos&#038;p=56312"},"modified":"2023-04-04T09:21:59","modified_gmt":"2023-04-04T12:21:59","slug":"sala-do-empreendedor","status":"publish","type":"carta-de-servicos","link":"https:\/\/www.apucarana.pr.gov.br\/site\/carta-de-servicos\/sala-do-empreendedor\/","title":{"rendered":"Sala do Empreendedor"},"content":{"rendered":"<p>A Sala do Empreendedor facilita os processos de abertura de empresas, regulariza\u00e7\u00e3o e baixa, bem como servi\u00e7os exclusivos aos Microempreendedores Individuais (MEI). Atua junto ao<span style=\"font-size: 1rem;\"> Fomento Paran\u00e1 para concess\u00e3o de cr\u00e9ditos e outros benef\u00edcios.<\/span><abbr title=\"Microempreendedores Individuais\"><\/abbr><\/p>\n<p><a href=\"\/saladoempreendedor\/\" target=\"_blank\" rel=\"noopener\">Clique aqui para conhecer o site da sala do empreendedor<\/a><\/p>\n","protected":false},"template":"","meta":[],"class_list":["post-56312","carta-de-servicos","type-carta-de-servicos","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/carta-de-servicos\/56312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/carta-de-servicos"}],"about":[{"href":"https:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/carta-de-servicos"}],"wp:attachment":[{"href":"https:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=56312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}