{"id":59362,"date":"2017-02-09T17:26:24","date_gmt":"2017-02-09T19:26:24","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=5540"},"modified":"2024-10-08T09:14:05","modified_gmt":"2024-10-08T12:14:05","slug":"dupla-de-apucarana-vence-etapa-inicial-do-transparana","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/dupla-de-apucarana-vence-etapa-inicial-do-transparana\/","title":{"rendered":"Dupla de Apucarana vence etapa inicial do Transparan\u00e1"},"content":{"rendered":"<p>Apucarana sediou ontem (8) a primeira das quatro etapas da 23\u00aa edi\u00e7\u00e3o do Rally Transparan\u00e1 de Regularidade. Participaram 60 ve\u00edculos reunindo os melhores pilotos e navegadores do pa\u00eds com disputas nas categorias master, graduados e turismo.<br \/>\nA categoria master teve como vencedores os apucaranenses Ot\u00e1vio \u201cMarreco\u201d Enz e Allan Enz. A dupla, atual campe\u00e3 do Transparan\u00e1, somou 45 pontos, seguida por Sandro Supitz e Robson Schuinka, de Cascavel, com 44; e Fl\u00e1vio Kath e Rafain Walendowsky, de Blumenau-SC, com 32.<br \/>\nLeandro Moor, o Ximura, de Apucarana, e Cl\u00e1udio Flores, de Itaja\u00ed-SC, ficaram na s\u00e9tima posi\u00e7\u00e3o, com os apucaranenses Roberto e Jhonatan Ardigo terminando a etapa em oitavo lugar.<br \/>\nPela categoria graduados os vencedores foram Victor Pudel e Claudemir Hubner, de Toledo, com Patrick Celeski e Felipe Pachewsky, de S\u00e3o Bento do Sul-SC, vencendo a etapa na categoria turismo.<br \/>\nA premia\u00e7\u00e3o aconteceu ontem (8) \u00e0 noite do Clube de Campo \u00c1gua Azul, com a presen\u00e7a do vice-prefeito, Junior da Femac, e da secret\u00e1ria do Esporte, Jossuela Pinheiro. \u201cPara n\u00f3s de Apucarana, prefeitura e Jeep Clube, \u00e9 uma alegria cada vez que essa competi\u00e7\u00e3o vem para c\u00e1. Aqui, a casa \u00e9 de voc\u00eas\u201d, disse Junior.<br \/>\nA segunda etapa do rally est\u00e1 acontecendo hoje de Apucarana a Tel\u00eamaco Borba. A terceira ocorre amanh\u00e3 com a prova saindo de Tel\u00eamaco Borba e chegando em Curitiba. A etapa final ser\u00e1 realizada neste s\u00e1bado na Capital do Estado, quando ser\u00e3o conhecidos os campe\u00f5es da 23\u00aa edi\u00e7\u00e3o nas categorias master, graduados e turismo.<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Participaram 60 ve\u00edculos reunindo os melhores pilotos e navegadores do pa\u00eds com disputas nas categorias master, graduados e turismo (Fotos &#8211; Profeta)<\/p>\n","protected":false},"author":4,"featured_media":5541,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-59362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/59362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=59362"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/59362\/revisions"}],"predecessor-version":[{"id":102568,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/59362\/revisions\/102568"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media\/5541"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=59362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=59362"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=59362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}