{"id":38432,"date":"2020-12-28T19:19:20","date_gmt":"2020-12-28T21:19:20","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=38432"},"modified":"2024-10-08T09:21:48","modified_gmt":"2024-10-08T12:21:48","slug":"sanepar-licita-1a-etapa-da-rede-de-esgoto-no-residencial-interlagos","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/sanepar-licita-1a-etapa-da-rede-de-esgoto-no-residencial-interlagos\/","title":{"rendered":"Sanepar licita 1a etapa da rede de esgoto no Residencial Interlagos"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\">A primeira etapa da implanta\u00e7\u00e3o da rede de esgoto no Residencial Interlagos atender\u00e1 300 domic\u00edlios. A Sanepar est\u00e1 realizando a licita\u00e7\u00e3o para contrata\u00e7\u00e3o da empresa que executar\u00e1 o servi\u00e7o e, ao todo, ser\u00e3o instalados 3,5 mil metros de coletores. O valor do investimento \u00e9 de cerca de R$ 1 milh\u00e3o.<\/p>\n<p align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: large;\">O prefeito Junior da Femac afirma que nesta fase ser\u00e3o atendidas as resid\u00eancias localizadas na parte alta do bairro, junto \u00e0 rua Cristiano Kussmaul. \u201cO esgoto ser\u00e1 levado por gravidade at\u00e9 a Esta\u00e7\u00e3o de Tratamento Barra Nova, situada nas proximidades do Cefas. Quando foi feita a moderniza\u00e7\u00e3o da Rua Cristiano Kussmaul, deixamos prontas as travessias para a rede de esgoto, instaladas com at\u00e9 sete metros de profundidade e com camisa de prote\u00e7\u00e3o, atrav\u00e9s de uma parceria com a Sanepar\u201d, frisa Junior da Femac, acrescentando que a previs\u00e3o de in\u00edcio das obras \u00e9 para o m\u00eas de abril.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: large;\">De acordo com Luiz Carlos Jacovassi, gerente regional da Sanepar, a licita\u00e7\u00e3o est\u00e1 na fase de recurso e de julgamento. \u201cEmpresas que participaram do certame ingressaram com recursos ao processo licitat\u00f3rio, o que dever\u00e1 atrasar um pouco o in\u00edcio das obras\u201d, pontua Jacovassi.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: 'Times New Roman', serif;\"><span style=\"font-size: large;\">O Residencial Interlagos tem cerca de 2 mil lotes e a Sanepar j\u00e1 trabalha no projeto que levar\u00e1 a rede de esgoto para todo o bairro. \u201cEste \u00e9 um projeto maior que necessitar\u00e1 da constru\u00e7\u00e3o de uma esta\u00e7\u00e3o elevat\u00f3ria para bombear os efluentes at\u00e9 a Esta\u00e7\u00e3o de Tratamento. Nesta segunda etapa tamb\u00e9m devem ser atendido o Jardim Veneza e outros bairros adjacentes.<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito Junior da Femac afirma que nesta fase ser\u00e3o atendidas as resid\u00eancias localizadas na parte alta do bairro, junto \u00e0 rua Cristiano Kussmaul (Foto: PMA\/arquivo)<\/p>\n","protected":false},"author":4,"featured_media":38433,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-38432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/38432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=38432"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/38432\/revisions"}],"predecessor-version":[{"id":99224,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/38432\/revisions\/99224"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=38432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=38432"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=38432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}