{"id":38380,"date":"2020-12-23T20:11:52","date_gmt":"2020-12-23T22:11:52","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=38380"},"modified":"2024-10-08T09:21:48","modified_gmt":"2024-10-08T12:21:48","slug":"prefeito-entrega-revisao-do-plano-diretor-na-camara-municipal","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/prefeito-entrega-revisao-do-plano-diretor-na-camara-municipal\/","title":{"rendered":"Prefeito entrega revis\u00e3o do plano diretor na C\u00e2mara Municipal"},"content":{"rendered":"<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">Num dos \u00faltimos passos no processo, o prefeito Junior da Femac entregou hoje (23) \u00e0 C\u00e2mara de Vereadores a revis\u00e3o do Plano Diretor Municipal composto de 11 leis. O presidente do Legislativo, Luciano Molina adiantou que a vota\u00e7\u00e3o do estudo vai acontecer em tr\u00eas sess\u00f5es extraordin\u00e1rias, nas pr\u00f3ximas ter\u00e7a-feira, quarta-feira e quinta-feira.<\/span><\/span><\/p>\n<p align=\"justify\">\u201c<span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">Quero parabenizar ao prefeito Junior da Femac pelo esfor\u00e7o em concluir plano diretor a tempo de ser votado ainda nesta gest\u00e3o do legislativo. Os vereadores acompanharam o processo da revis\u00e3o desse t\u00e3o importante estudo voltado ao planejamento do futuro da cidade e podem fazer uma an\u00e1lise com mais conhecimento do que est\u00e1 nas leis\u201d, disse Molina.<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">Junior da Femac destacou a qualidade t\u00e9cnica e ampla participa\u00e7\u00e3o popular no processo de elabora\u00e7\u00e3o da revis\u00e3o do Plano Diretor. \u201cMesmo com a pandemia, n\u00e3o ficamos parados e pudemos concluir esse estudo. Precisamos que a cidade esteja pronta tamb\u00e9m na esfera das leis para retomada do desenvolvimento na p\u00f3s-pandemia\u201d, afirmou.<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\">Depois <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"pt-BR\">de <\/span><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\">meses de estudos e a realiza\u00e7\u00e3o de 74 eventos entre reuni\u00f5es e audi\u00eancias p\u00fablicas, a revis\u00e3o geral do plano diretor municipal de Apucarana foi entregue ao executivo na tarde de ontem (22) pela empresa <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"pt\">respons\u00e1vel pela elabora\u00e7\u00e3o do plano, a DRZ Tecnologia. Ap\u00f3s an\u00e1lise e vota\u00e7\u00e3o da c\u00e2mara municipal o plano segue para san\u00e7\u00e3o do prefeito Junior da Femac.<\/span><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudo est\u00e1 na pauta de vota\u00e7\u00e3o em tr\u00eas sess\u00f5es extraordin\u00e1rias, na ter\u00e7a, quarta e quinta-feira da pr\u00f3xima semana<\/p>\n","protected":false},"author":4,"featured_media":38381,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-38380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/38380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=38380"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/38380\/revisions"}],"predecessor-version":[{"id":99227,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/38380\/revisions\/99227"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=38380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=38380"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=38380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}