{"id":38209,"date":"2020-12-18T16:12:48","date_gmt":"2020-12-18T18:12:48","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=38209"},"modified":"2024-10-08T09:21:49","modified_gmt":"2024-10-08T12:21:49","slug":"prefeitura-e-sivale-planejam-implantacao-da-feira-da-roupa","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/prefeitura-e-sivale-planejam-implantacao-da-feira-da-roupa\/","title":{"rendered":"Prefeitura e Sivale planejam implanta\u00e7\u00e3o da Feira da Roupa"},"content":{"rendered":"<p>Assim que houver a vacina contra o coronav\u00edrus, Prefeitura de Apucarana e o Sindicato das Ind\u00fastrias do Vestu\u00e1rio de Apucarana e Vale do Iva\u00ed (Sivale) querem estar com tudo pronto para o lan\u00e7amento da Feira da Roupa. A inten\u00e7\u00e3o \u00e9 promover periodicamente o evento no Espa\u00e7o das Feiras, recebendo compradores do Paran\u00e1 e tamb\u00e9m de outras regi\u00f5es do Pa\u00eds.<br \/>\nO assunto foi debatido nesta sexta-feira (18\/12) pelo prefeito de Apucarana, Junior da Femac, e por Elizabete Ardigo, presidente do Sivale. \u201cApucarana \u00e9 a maior produtora de roupas do Paran\u00e1, mas falta um ponto de comercializa\u00e7\u00e3o que atraia os compradores. Esse espa\u00e7o ser\u00e1 a Feira da Roupa, a exemplo do que j\u00e1 existe em outros locais do Pa\u00eds, como Santa Cruz do Capibaribe, no estado de Pernambuco, e Brusque e Jaragu\u00e1 do Sul, em Santa Catarina. E para que possamos chegar a estes patamares, tem que haver um come\u00e7o\u201d, pontua Junior da Femac.<br \/>\nNo in\u00edcio de janeiro, a Feira da Roupa ser\u00e1 formatada, com a defini\u00e7\u00e3o da periodicidade, dias e hor\u00e1rios de funcionamento. \u201cO Munic\u00edpio est\u00e1 colocando, gratuitamente, \u00e0 disposi\u00e7\u00e3o os 38 estandes da parte seca do Espa\u00e7o das Feiras e caber\u00e1 ao Sivale fazer a chamada dos interessados e definir os crit\u00e9rios de participa\u00e7\u00e3o\u201d, adianta Junior da Femac.<br \/>\nO prefeito de Apucarana tamb\u00e9m colocou o Munic\u00edpio \u00e0 disposi\u00e7\u00e3o para contribuir com a divulga\u00e7\u00e3o da feira, a exemplo do que est\u00e1 fazendo neste final de ano com a campanha \u201cNatal de Esperan\u00e7a\u201d. \u201cQueremos dar visibilidade ao que \u00e9 produzido em Apucarana, com a presen\u00e7a na feira de personalidades nacionais e estaduais, e impulsionar a cria\u00e7\u00e3o e produ\u00e7\u00e3o de marcas pr\u00f3prias\u201d, frisa Junior da Femac.<br \/>\nA presidente do Sivale recebeu com entusiasmo a iniciativa de implanta\u00e7\u00e3o da Feira da Roupa. \u201c\u00c9 um projeto maravilhoso, beneficiando as ind\u00fastrias da confec\u00e7\u00e3o que poder\u00e3o expor os seus produtos, dando visibilidade \u00e0s suas marcas e fortalecendo ainda mais Apucarana como a capital da confec\u00e7\u00e3o\u201d, frisa Elizabete Ardigo.<br \/>\nA presidente do Sivale afirma que a inten\u00e7\u00e3o tamb\u00e9m \u00e9 buscar apoio em outros \u00f3rg\u00e3os, como o Sebrae e a Federa\u00e7\u00e3o das Ind\u00fastrias do Estado do Paran\u00e1 (Fiep), para viabilizar a feira. \u201cQueremos organizar e trazer caravanas de outras cidades para a Feira da Roupa em Apucarana. Ap\u00f3s realizarmos o enfrentamento da pandemia, vamos come\u00e7ar essa feira com for\u00e7a total. Isso ser\u00e1 excelente em termos de visibilidade, vendas e o crescimento das empresas\u201d, reitera.<br \/>\nElisabete tamb\u00e9m agradeceu a parceria entre a Prefeitura e o Sivale, citando como exemplo o apoio recebido para a produ\u00e7\u00e3o de m\u00e1scaras. \u201cO setor se adaptou rapidamente e hoje j\u00e1 existem muitas empresas estruturadas, que investiram na aquisi\u00e7\u00e3o de m\u00e1quinas importadas, no registro na Anvisa e na participa\u00e7\u00e3o de licita\u00e7\u00f5es. O setor se reinventou e conseguiu enfrentar a crise\u201d, avalia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A inten\u00e7\u00e3o \u00e9 promover periodicamente o evento no Espa\u00e7o das Feiras, recebendo compradores do Paran\u00e1 e tamb\u00e9m de outras regi\u00f5es do Pa\u00eds (Foto: PMA)<\/p>\n","protected":false},"author":4,"featured_media":38212,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-38209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/38209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=38209"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/38209\/revisions"}],"predecessor-version":[{"id":99240,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/38209\/revisions\/99240"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=38209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=38209"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=38209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}