{"id":38184,"date":"2020-12-17T18:47:00","date_gmt":"2020-12-17T20:47:00","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=38184"},"modified":"2024-10-08T09:21:50","modified_gmt":"2024-10-08T12:21:50","slug":"ubs-do-sumatra-e-alvo-de-vandalismo","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/ubs-do-sumatra-e-alvo-de-vandalismo\/","title":{"rendered":"UBS do Sumatra \u00e9 alvo de vandalismo"},"content":{"rendered":"<p class=\"western\" align=\"justify\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\">A Unidade B\u00e1sica de Sa\u00fade (UBS) Eunice Penharbel, do Residencial Sumatra, foi alvo de vanda<\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"pt-BR\">l<\/span><\/span><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\">ismo na madrugada desta quinta-feira. O vidro da porta central da unidade foi destru\u00eddo e os <\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"pt-BR\">depredadores <\/span><\/span><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\">s\u00f3 n\u00e3o deram mais preju<\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"pt-BR\">\u00ed<\/span><\/span><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\">zo aos cofres p\u00fablicos porque n\u00e3o conseguiram romper a grade de ferro que refor\u00e7a a \u00e1rea de entrada. <\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"pt-BR\">O<\/span><\/span><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"> ato de vandalismo aconteceu menos de um m\u00eas depois que outra UBS, a da Vila Regina, tamb\u00e9m teve os vidros das janelas quebrados. Esta unidade acabou de passar por uma obra de amplia\u00e7\u00e3o e reforma geral e sua inaugura\u00e7\u00e3o ser\u00e1 agendada para breve.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"pt-BR\">Tamb\u00e9m h\u00e1 cerca de dois meses, o<\/span><\/span><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"> atendimento odontol\u00f3gico da UBS P<\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\">hilipe Weckewerth, no Jardim Milani, permaneceu interrompido depois que o compressor de ar do consult\u00f3rio odontol\u00f3gico foi furtado da unidade.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\">O diretor presidente da Autarquia Municipal de Sa\u00fade (AMS), Roberto Kaneta, lamenta a ocorr\u00eancia lembrando que os pr\u00e9dios p\u00fablicos prestam atendimento \u00e0 popula\u00e7\u00e3o. \u201cOs usu\u00e1rios da sa\u00fade s\u00e3o os mais prejudicados. A sa\u00fade, um servi\u00e7o t\u00e3o essencial a comunidade, sofrer atos de vandalismo \u00e9 altamente conden\u00e1vel. Quando isso ocorre, o atendimento \u00e9 prejudicado e <\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\">at\u00e9<\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"> mesmo interrompido j\u00e1 que \u00e9 necess\u00e1rio algum tempo para os reparos e certos casos dependem de processo licitat\u00f3rio\u201d, afirma Kaneta.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\">O vice-presidente da AMS, Em\u00eddio Bachiega, pede para que a popula\u00e7\u00e3o ajude a cuidar dos pr\u00e9dios p\u00fablicos. \u201cSe virem alguma situa\u00e7\u00e3o suspeita liguem para a Guarda Municipal no 153 ou para Pol\u00edcia Militar no 190\u201d, orienta Bachiega.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\">A reposi\u00e7\u00e3o do equipamento necessitava seguir os tr\u00e2mites exigidos nas compras do poder p\u00fablico, n\u00e3o acontecendo com a rapidez que a situa\u00e7\u00e3o requer. Na UBS Eunice Penhabel, o atendimento sofreu um atraso na manh\u00e3 de hoje pois o servi\u00e7o de limpeza dos vidros <\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"pt-BR\">estilha\u00e7ados<\/span><\/span><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"> precisou de ser cuidadoso para n\u00e3o correr o risco de ferir os pacientes. <\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vidro da porta central da unidade foi quebrado por depredadores<\/p>\n","protected":false},"author":4,"featured_media":38185,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-38184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/38184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=38184"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/38184\/revisions"}],"predecessor-version":[{"id":99244,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/38184\/revisions\/99244"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=38184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=38184"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=38184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}