{"id":37861,"date":"2020-12-07T19:34:40","date_gmt":"2020-12-07T21:34:40","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=37861"},"modified":"2024-10-08T09:21:52","modified_gmt":"2024-10-08T12:21:52","slug":"espaco-das-feiras-e-centro-do-idoso-sao-alvo-de-criminosos","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/espaco-das-feiras-e-centro-do-idoso-sao-alvo-de-criminosos\/","title":{"rendered":"&quot;Espa\u00e7o das Feiras&quot; e &quot;Centro do Idoso&quot; s\u00e3o alvo de criminosos"},"content":{"rendered":"<p>A Pol\u00edcia Civil de Apucarana investiga a autoria de dois crimes contra o patrim\u00f4nio p\u00fablico ocorridos neste final de semana. Segundo boletim de ocorr\u00eancia registrado nesta segunda-feira (07\/12), criminosos agiram no recinto do Espa\u00e7o das Feiras, localizado na \u00e1rea central, e tamb\u00e9m no Centro de Conviv\u00eancia do Idoso, no Jardim Aeroporto.<br \/>\nEm constru\u00e7\u00e3o na Rua Talita Bresolin, ao lado do Cemit\u00e9rio Municipal da Saudade, o Espa\u00e7o das Feiras teve parte da rede el\u00e9trica furtada. &#8220;A a\u00e7\u00e3o aconteceu na madrugada de domingo. Os bandidos levaram uma grande quantidade de fios da rede subterr\u00e2nea, respons\u00e1vel pelo sistema que alimenta a ilumina\u00e7\u00e3o do complexo, cuja edifica\u00e7\u00e3o est\u00e1 na fase final&#8221;, informa o engenheiro eletricista Lafayete dos Santos Luz, diretor-presidente do Instituto de Desenvolvimento, Pesquisa e Planejamento de Apucarana (Idepplan). O boletim de ocorr\u00eancia foi registrado pela empreiteira respons\u00e1vel pela obra.<br \/>\nJ\u00e1 no Centro de Conviv\u00eancia do Idoso, os criminosos entraram pelo telhado, danificando parte da forra\u00e7\u00e3o e furtando uma s\u00e9rie de equipamentos. &#8220;Foram duas a\u00e7\u00f5es na mesma semana. Na primeira levaram todas as l\u00e2mpadas do sal\u00e3o de eventos e, neste final de semana, furtaram uma geladeira, uma tenda de metal sanfonada, poltronas de repouso dos idosos, material das aulas de esporte e material de expediente, al\u00e9m de danificar utens\u00edlios da cozinha, espalhar alimentos pelo ch\u00e3o e deixar muita sujeira&#8221;, relata a assistente social Ana Paula Nazarko, secret\u00e1ria Municipal da Assist\u00eancia Social.<br \/>\nEm ambos locais a prefeitura refor\u00e7ou a vigil\u00e2ncia. &#8220;Crime contra o patrim\u00f4nio p\u00fablico \u00e9 um crime contra toda a popula\u00e7\u00e3o. Pe\u00e7o que se algu\u00e9m souber de algo, colabore com as investiga\u00e7\u00f5es, repassando informa\u00e7\u00f5es que possam colaborar para que os autores destes crimes sejam identificados e punidos de acordo com a lei&#8221;, disse o prefeito J\u00fanior da Femac. O telefone da Pol\u00edcia Civil \u00e9 197.<br \/>\nA orienta\u00e7\u00e3o da Prefeitura de Apucarana \u00e9 de que Guarda Civil Municipal (GCM) deve ser acionada quando houver suspeita de uma poss\u00edvel a\u00e7\u00e3o criminosa em pr\u00e9dios e espa\u00e7os p\u00fablicos. &#8220;Sempre que a pessoa verificar uma movimenta\u00e7\u00e3o diferente, \u00e9 importante que ela acione a Guarda Municipal pelo telefone 153, para que ela fa\u00e7a, preventivamente, o patrulhamento e abordagens necess\u00e1rias&#8221;, pontua o prefeito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guarda Civil Municipal (GCM) deve ser acionada pelo telefone 153 sempre que houver suspeita de uma poss\u00edvel a\u00e7\u00e3o criminosa em pr\u00e9dios e espa\u00e7os p\u00fablicos (Foto: PMA)<\/p>\n","protected":false},"author":4,"featured_media":37865,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-37861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/37861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=37861"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/37861\/revisions"}],"predecessor-version":[{"id":99273,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/37861\/revisions\/99273"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=37861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=37861"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=37861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}