{"id":37817,"date":"2020-12-04T18:55:32","date_gmt":"2020-12-04T20:55:32","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=37817"},"modified":"2024-10-08T09:21:52","modified_gmt":"2024-10-08T12:21:52","slug":"selo-sesi-ods-2020-reconhece-quatro-acoes-de-apucarana","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/selo-sesi-ods-2020-reconhece-quatro-acoes-de-apucarana\/","title":{"rendered":"Selo Sesi ODS 2020 reconhece quatro a\u00e7\u00f5es de Apucarana"},"content":{"rendered":"<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">Quatro <\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">a\u00e7\u00f5es<\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"> de Apucarana conquistaram o <\/span><\/span><span style=\"color: #53585e;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">Selo Sesi ODS 2020, <\/span><\/span><\/span><span style=\"color: #53585e;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">que entra neste ano na sua quinta edi\u00e7\u00e3o.<\/span><\/span><\/span> <span style=\"color: #53585e;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">Trata-se de<\/span><\/span><\/span> <span style=\"color: #53585e;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">uma iniciativa do Sistema Fiep, por meio do Sesi <\/span><\/span><\/span><span style=\"color: #53585e;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">que reconhece ind\u00fastrias, empresas, institui\u00e7\u00f5es p\u00fablicas, organiza\u00e7\u00f5es da sociedade civil e institui\u00e7\u00f5es de ensino p\u00fablicas e privadas que est\u00e3o atuando em prol do alcance dos Objetivos de Desenvolvimento Sustent\u00e1vel da ONU. Devido \u00e0 pandemia, o foco deste ano foram as a\u00e7\u00f5es relacionadas ao coronav\u00edrus.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">O recebimento do <span style=\"color: #53585e;\">Selo Sesi ODS 2020 <\/span><span style=\"color: #53585e;\">veio atrav\u00e9s a\u00e7\u00f5es da Autarquia Municipal de Sa\u00fade, Autarquia Municipal de Educa\u00e7\u00e3o, Idepplan\/Secretaria da Fazenda e prefeitura.\u00a0<\/span><\/span><\/span>\u201c<span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">\u00c9 um reconhecimento muito grande, em especial neste ano em que os pr\u00eamios foram focados na pandemia. Entre centenas de a\u00e7\u00f5es apresentadas no estado, quadro ligadas a prefeitura de nossa cidade foram selecionadas para receber esse <span style=\"color: #53585e;\">reconhecimento de tanta relev\u00e2ncia\u201d, comemora o prefeito Junior da Femac.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #53585e;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">Junior destaca que <\/span><\/span><\/span><span style=\"color: #53585e;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">os<\/span><\/span><\/span><span style=\"color: #53585e;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"> ODS s\u00e3o definid<\/span><\/span><\/span><span style=\"color: #53585e;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">o<\/span><\/span><\/span><span style=\"color: #53585e;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">s pela Organiza\u00e7\u00e3o Mundial de Sa\u00fade, com crit\u00e9rios r\u00edgidos. \u201cQuando uma iniciativa obt\u00e9m esse reconhecimento \u00e9 algo grandioso e recompensador\u201d, afirma Junior da Femac.<\/span><\/span><\/span><span style=\"color: #ffffff;\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">vento ser\u00e1 realizado de <\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">No r<\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">elat\u00f3rio <\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">de<\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"> boas pr\u00e1ticas <\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">do<\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"> Selo Sesi ODS 2020 relacionadas a preven\u00e7\u00e3o da Covid-19 <\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">est\u00e3o\u00a0as seguintes\u00a0a\u00e7\u00f5es de Apucarana:<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><b>Educa\u00e7\u00e3o Integral em Tempos de Pandemia<\/b>: A Autarquia Municipal de Educa\u00e7\u00e3o de Apucarana vem garantindo aos alunos, al\u00e9m do direito \u00e0 aprendizagem, a promo\u00e7\u00e3o da sa\u00fade nutricional e psicol\u00f3gica durante a pandemia. Diariamente, s\u00e3o disponibilizadas v\u00eddeo-aulas com atividades pedag\u00f3gicas, envolvendo conte\u00fados essenciais para cada idade escolar, por meio da Plataforma Educacional Google Class Room. Os alunos t\u00eam recebido aulas de qualidade, que tamb\u00e9m s\u00e3o disponibilizadas de forma impressa e pela TV. <\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><b>Pronto atendimento de combate ao Coronav\u00edrus<\/b>: Apucarana foi, por meio da Autarquia Municipal de Sa\u00fade, uma das primeiras cidades do interior do Paran\u00e1 a implantar um pronto atendimento central para acolhimento das demandas suspeitas e confirmadas de casos da Covid-19. A implanta\u00e7\u00e3o teve por objetivo reduzir a busca de atendimento nas UBS e na UPA, e assim, reorganizar o fluxo, a circula\u00e7\u00e3o de indiv\u00edduos contaminados promovendo a detec\u00e7\u00e3o precoce dos casos para ado\u00e7\u00e3o de conduta terap\u00eautica. Instituiu-se os servi\u00e7os de monitoramento e teleatendimento para fortalecer as a\u00e7\u00f5es de combate a pandemia.<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><b>Apucarana Unida em Defesa do Emprego: <\/b>Desde o in\u00edcio da pandemia, o Munic\u00edpio de Apucarana, atrav\u00e9s do Idepplan e Secretaria da Fazenda, manteve o cuidado com a sa\u00fade e tamb\u00e9m com as empresas, buscando garantir a manuten\u00e7\u00e3o dos empregos. Desta forma criou, no sagu\u00e3o da Prefeitura, o pronto atendimento ao Programa Paran\u00e1 Recupera, um sistema de atendimento para ajudar e facilitar as pessoas a chegarem at\u00e9 a linha de cr\u00e9dito emergencial destinada a preserva\u00e7\u00e3o de sal\u00e1rios e empregos em empreendimentos informais, MEI, Micro e Pequenas Empresas.<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"><b>Apucarana Todos Juntos no Combate ao Coronav\u00edrus: <\/b><\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">A prefeitura adquiriu<\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\"> 170 mil m\u00e1scaras de tecido para distribui\u00e7\u00e3o \u00e0 popula\u00e7\u00e3o, juntamente com panfleto informativo das medidas de preven\u00e7\u00e3o. Com o apoio do 30\u00ba Batalh\u00e3o de Infantaria Mecanizado (BIMec) as m\u00e1scaras foram distribu\u00eddas gratuitamente para todos os cidad\u00e3os. Tamb\u00e9m foram entregues sabonetes l\u00edquidos, para conscientiza\u00e7\u00e3o da import\u00e2ncia da higieniza\u00e7\u00e3o das m\u00e3os. Pelo site: http:\/\/www.apucarana.pr.gov.br\/site\/coronavirus a popula\u00e7\u00e3o pode acompanhar a evolu\u00e7\u00e3o dos casos e todos os servi\u00e7os dispon\u00edveis no enfrentamento ao novo coronav\u00edrus. Ainda no Canal oficial nas redes sociais sobre a Covid-19 pelo https:\/\/www.facebook.com\/covidapucarana <\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">\u00e9 <\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: large;\">divulgado boletins di\u00e1rios da evolu\u00e7\u00e3o da doen\u00e7a no munic\u00edpio, estat\u00edsticas, formas de preven\u00e7\u00e3o e a\u00e7\u00f5es da administra\u00e7\u00e3o no combate \u00e0 pandemia. Por meio da Secretaria de Assist\u00eancia Social, foram distribu\u00eddas cestas b\u00e1sicas \u00e0s fam\u00edlias em situa\u00e7\u00e3o de vulnerabilidade social, tendo em vista o aumento da necessidade em virtude da pandemia. <\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aulas on-line, pronto atendimento, defesa dos empregados e distribui\u00e7\u00e3o de m\u00e1scaras foram destacados pelo Sesi<\/p>\n","protected":false},"author":4,"featured_media":37818,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-37817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/37817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=37817"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/37817\/revisions"}],"predecessor-version":[{"id":99276,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/37817\/revisions\/99276"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=37817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=37817"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=37817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}