{"id":36147,"date":"2020-08-12T18:58:10","date_gmt":"2020-08-12T21:58:10","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=36147"},"modified":"2024-10-08T09:21:57","modified_gmt":"2024-10-08T12:21:57","slug":"prefeitura-firma-convenio-com-sebrae-para-planejamento-da-retomada-da-economia","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/prefeitura-firma-convenio-com-sebrae-para-planejamento-da-retomada-da-economia\/","title":{"rendered":"Prefeitura firma conv\u00eanio com Sebrae para planejamento da retomada da economia"},"content":{"rendered":"<p>O prefeito Junior da Femac, atrav\u00e9s do Instituto de Desenvolvimento, Pesquisa e Planejamento (Idepplan) assinou hoje (12) um conv\u00eanio com o Sebrae para elabora\u00e7\u00e3o de um Programa de Retomada da Economia P\u00f3s-Pandemia. A iniciativa come\u00e7ou ser discutida pela administra\u00e7\u00e3o municipal h\u00e1 um m\u00eas com a participa\u00e7\u00e3o de representantes do setor produtivo.<br \/>\nO conv\u00eanio estabelece que o Sebrae executar\u00e1 um trabalho dividido em tr\u00eas fases. Primeiramente ser\u00e1 realizado um levantamento do impacto econ\u00f4mico que a pandemia gerou no munic\u00edpio.<br \/>\nO pr\u00f3ximo passo ser\u00e1 criar uma for\u00e7a tarefa, para elaborar um planejamento de enfrentamento do impacto negativo no setor produtivo, direcionando as a\u00e7\u00f5es em favor de todos os segmentos econ\u00f4micos da cidade. E ainda caber\u00e1 ao Sebrae fazer o acompanhamento da execu\u00e7\u00e3o deste planejamento.<br \/>\n\u201cO Sebrae vai nos ajudar\u00a0 com dados do impacto da pandemia nosso com\u00e9rcio, servi\u00e7os e ind\u00fastrias. Com base nestas informa\u00e7\u00f5es formaremos uma for\u00e7a tarefa com a participa\u00e7\u00e3o da prefeitura e do setor produtivo. Vamos definir juntos a tomada de decis\u00f5es para alavancar os neg\u00f3cios em cada setor\u201d, afirmou o prefeito Junior da Femac.<br \/>\n\u201cQueremos que o levantamento das informa\u00e7\u00f5es junto aos comerciantes, prestadores de servi\u00e7os e ind\u00fastrias seja iniciado de imediato. Nossa inten\u00e7\u00e3o \u00e9 fazer tudo o que for poss\u00edvel para fomentar as nossas atividades econ\u00f4micas, sempre respeitando as recomenda\u00e7\u00f5es restritivas da sa\u00fade\u201d, acrescentou Junior da Femac.<br \/>\nO presidente da ACIA, Jaime Leonel, parabenizou o prefeito pela iniciativa. \u201cPrecisamos atender as empresas que foram mais impactadas pela pandemia e hoje demos um passo importante para que as a\u00e7\u00f5es a serem tomadas sejam amparadas em um estudo da real situa\u00e7\u00e3o de cada setor produtivo\u201d, disse Jaime Leone.<br \/>\nA assinatura do conv\u00eanio, com o repasse de R$ 20 mil da prefeitura ao Sebrae para execu\u00e7\u00e3o deste estudo, teve a participa\u00e7\u00e3o do\u00a0 presidente da Associa\u00e7\u00e3o Comercial, Industrial e de Servi\u00e7os de Apucarana (Acia), Jayme Leonel; o vice da Acia, Wanderlei Faganello; e de Tiago Cunha, do Sebrae.<br \/>\n&nbsp;<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um estudo vai avaliar o impacto da pandemia no setor produtivo da cidade e definir a\u00e7\u00f5es para recupera\u00e7\u00e3o<\/p>\n","protected":false},"author":4,"featured_media":36148,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-36147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/36147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=36147"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/36147\/revisions"}],"predecessor-version":[{"id":99332,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/36147\/revisions\/99332"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=36147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=36147"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=36147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}