{"id":36011,"date":"2020-08-07T20:36:23","date_gmt":"2020-08-07T23:36:23","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=36011"},"modified":"2024-10-08T09:21:58","modified_gmt":"2024-10-08T12:21:58","slug":"liderancas-aprovam-medidas-de-enfrentamento-ao-coronavirus","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/liderancas-aprovam-medidas-de-enfrentamento-ao-coronavirus\/","title":{"rendered":"Lideran\u00e7as aprovam medidas de enfrentamento ao Coronav\u00edrus"},"content":{"rendered":"<p style=\"font-weight: 400;\">Neste domingo, dia 9 de agosto, est\u00e3o sendo completados quatro meses da confirma\u00e7\u00e3o do primeiro caso do novo Coronav\u00edrus (Covid-19) em Apucarana. Neste per\u00edodo, a Prefeitura de Apucarana, por meio da Autarquia Municipal de Sa\u00fade (AMS) se estruturou, gradativamente, para o enfrentamento da pandemia e muitas a\u00e7\u00f5es foram empreendidas.<\/p>\n<p style=\"font-weight: 400;\">Passados 120 dias, Apucarana acumula 725 pessoas contaminadas, 589 curadas, 813 em isolamento no momento e 20 \u00f3bitos. \u201cNeste per\u00edodo, ampliamos o di\u00e1logo com lideran\u00e7as e a popula\u00e7\u00e3o. Com base nestas intera\u00e7\u00f5es e no monitoramento constante dos n\u00fameros, foram definidas uma s\u00e9rie de medidas sanit\u00e1rias e elaborado um plano de enfrentamento\u201d, comenta o prefeito Junior da Femac.<\/p>\n<p style=\"font-weight: 400;\">Outras lideran\u00e7as de Apucarana avaliam que o enfrentamento do Coronav\u00edrus vem sendo conduzido de forma adequada, destacando principalmente o canal de di\u00e1logo existente, o trabalho de conscientiza\u00e7\u00e3o realizado e a transpar\u00eancia no repasse das informa\u00e7\u00f5es. Al\u00e9m das medidas sanit\u00e1rias, outro aspecto ressaltado foram as a\u00e7\u00f5es desenvolvidas visando garantir a manuten\u00e7\u00e3o de empregos.<\/p>\n<p style=\"font-weight: 400;\">\u201cA situa\u00e7\u00e3o est\u00e1 sendo administrada de forma adequada, e, gra\u00e7as a este enfrentamento, a situa\u00e7\u00e3o n\u00e3o fugiu do controle e, at\u00e9 que se crie uma vacina, estamos conseguindo conviver com o v\u00edrus\u201d, avalia o empres\u00e1rio Jayme Leonel, presidente da Associa\u00e7\u00e3o, Comercial, Industrial e de Servi\u00e7os de Apucarana (Acia).<\/p>\n<p style=\"font-weight: 400;\">Jayme Leonel tamb\u00e9m salienta que as medidas permitiram a retomada da atividade econ\u00f4mica, seguindo-se os protocolos recomendados. \u201cTudo est\u00e1 sendo feito dentro do poss\u00edvel, com o monitoramento di\u00e1rio dos \u00edndices e com o di\u00e1logo permanente com a sociedade. Esperamos que esse canal permane\u00e7a aberto e que as lideran\u00e7as continuem sendo ouvidas, para que as a\u00e7\u00f5es sejam consenso e tomadas de forma organizada\u201d, pondera Jayme Leonel.<\/p>\n<p style=\"font-weight: 400;\">\u00a0A irm\u00e3 Geovana Ramos, diretora-geral do Hospital da Provid\u00eancia, destaca as a\u00e7\u00f5es de enfrentamento, como a cria\u00e7\u00e3o do Pronto Atendimento do Coronav\u00edrus, as lives di\u00e1rias de conscientiza\u00e7\u00e3o do prefeito Junior da Femac sobre as medidas e protocolos a serem seguidos e o aumento do n\u00famero de leitos hospitalares. \u201cApucarana est\u00e1 no caminho certo. Estamos passando agora pela fase mais cr\u00edtica e o Hospital se preparou para esse momento. No entanto, a gente sabe que poderia estar muito pior caso as medidas de enfrentamento n\u00e3o tivessem sido adotadas. Agora \u00e9 momento de manter tudo o que foi feito, respeitando rigorosamente os protocolos\u201d, frisa a irm\u00e3 Geovana.<\/p>\n<p style=\"font-weight: 400;\"><strong>MEDIDAS DO P\u00d3S-PANDEMIA<\/strong>\u00a0&#8211; O prefeito Junior da Femac pondera que a pandemia do Novo Coronavirus tem como um dos principais efeitos, a redu\u00e7\u00e3o das atividades econ\u00f4micas. Segundo ele, isso afeta todos os setores mais, sobretudo, o com\u00e9rcio e os prestadores de servi\u00e7os.<\/p>\n<p style=\"font-weight: 400;\">\u201cA partir de agora, ter\u00e3o de ser adotadas novas medidas, em conjunto pelo setor do Com\u00e9rcio, da Ind\u00fastria, Agroind\u00fastria, Agricultura e Pecu\u00e1ria e pelo setor dos servi\u00e7os. Por isso, j\u00e1 h\u00e1 alguns dias convoquei lideran\u00e7as do setor produtivo, para estruturarmos um grupo de trabalho que acompanhar\u00e1 as medidas que visam dinamizar a economia no p\u00f3s-pandemia\u201d, anuncia Junior.<\/p>\n<p style=\"font-weight: 400;\">O prefeito revela que, a prefeitura por meio do Idepplan, firmou convenio como Sebrae para que seja feito um diagn\u00f3stico de quais setores da economia foram mais afetados pela Pandemia. \u201cEstas duas medidas, ou seja, a forma\u00e7\u00e3o do grupo de trabalho e o conv\u00eanio com o Sebrae \u00a0j\u00e1 est\u00e3o em andamento\u201d, assinala.<\/p>\n<p style=\"font-weight: 400;\">Nestes 120 dias ap\u00f3s o surgimento do primeiro caso de contamina\u00e7\u00e3o, Apucarana foi uma das cidades de m\u00e9dio e grande porte que fecharam por menor tempo os v\u00e1rios setores da economia. \u201cO pacote de obras da prefeitura n\u00e3o parou, contribuindo para a manuten\u00e7\u00e3o de centenas de empregos. S\u00e3o escolas, UBS, Pavimenta\u00e7\u00e3o e Obras em geral\u201d.<\/p>\n<p style=\"font-weight: 400;\">Junior da Femac lembra que o poder p\u00fablico estimulou o setor do vestu\u00e1rio de Apucarana a come\u00e7ar a produzir m\u00e1scaras. E a prefeitura fez as primeiras compras. \u201cHoje Apucarana que \u00e9 a maior produtora de roupas do Paran\u00e1, \u00e9 tamb\u00e9m uma das maiores produtoras de mascaras do Estado. Esta medida ajudou a preservar milhares de empregos.<\/p>\n<p style=\"font-weight: 400;\">A Prefeitura comprou 100 mil m\u00e1scaras descart\u00e1veis e 170 mil m\u00e1scaras de tecido, que foram distribu\u00eddas para a popula\u00e7\u00e3o. \u201cMantivemos o pagamento dos terceirizados da Prefeitura para evitar o desemprego. A C\u00e2mara aprovou nosso Projeto de Lei e com isso conseguimos pagar professores da hidrogin\u00e1stica e nata\u00e7\u00e3o, o pessoal que faz o transporte escolar, professores de m\u00fasica e de dan\u00e7a e, enfim, todos os terceirizados da prefeitura\u201d, recorda Junior.<\/p>\n<p style=\"font-weight: 400;\">Neste per\u00edodo a prefeitura comprou os produtos da agricultura familiar para entregar lotes para fam\u00edlias de alunos das escolas municipais, contribuindo para manter o emprego e a renda no campo.<\/p>\n<p style=\"font-weight: 400;\">A prefeitura tamb\u00e9m estruturou o atendimento para a libera\u00e7\u00e3o da linha de cr\u00e9dito do \u201cParan\u00e1 Recupera\u201d. Os servidores foram treinados para o atendimento no setor t\u00e9rreo da prefeitura. \u201cSomos a cidade do Paran\u00e1 com maior n\u00famero de contratos assinados, s\u00f3 ficamos atr\u00e1s da Capital. S\u00e3o 1.140 contratos assinados, com empresas de pequeno porte, MEI`S, profissionais liberais formalizados ou n\u00e3o. Chegamos a R$ 6 (seis) milh\u00f5es de contratos\u201d, diz Junior, acrescentando que, com isso foi poss\u00edvel manter muitas pequenas empresas e empregos.<\/p>\n<p style=\"font-weight: 400;\">\u201cAinda nestes 120 dias, pagamos todos os fornecedores em dia e os sal\u00e1rios dos servidores em dia. Sempre insistindo para que todos gastassem em Apucarana para manter os nossos empregos\u201d, lembra o prefeito.<\/p>\n<p style=\"font-weight: 400;\"><strong>OUTRAS MEDIDAS ADOTADAS<\/strong>:<\/p>\n<ul>\n<li style=\"font-weight: 400;\">Cria\u00e7\u00e3o do Pronto Atendimento Municipal do Coronav\u00edrus<\/li>\n<li style=\"font-weight: 400;\">Destina\u00e7\u00e3o de ambul\u00e2ncias exclusivas para o atendimento na pandemia<\/li>\n<li style=\"font-weight: 400;\">Contrata\u00e7\u00e3o de mais m\u00e9dicos, enfermeiros e auxiliares de enfermagem<\/li>\n<li style=\"font-weight: 400;\">Compra de v\u00e1rios lotes de testes r\u00e1pidos do Coronav\u00edrus<\/li>\n<li style=\"font-weight: 400;\">Vacina\u00e7\u00e3o contra a Gripe, atingindo 94,8% do p\u00fablico alvo<\/li>\n<li style=\"font-weight: 400;\">Amplia\u00e7\u00e3o dos leitos normais e de UTI para pacientes do coronav\u00edrus<\/li>\n<li style=\"font-weight: 400;\">Instala\u00e7\u00e3o de totens com \u00e1lcool em gel nos principais pr\u00e9dios p\u00fablicos e no terminal de transporte urbano<\/li>\n<li style=\"font-weight: 400;\">Fiscaliza\u00e7\u00e3o di\u00e1ria e cont\u00ednua para cumprimento de hor\u00e1rios e de outras normas preventivas<\/li>\n<li style=\"font-weight: 400;\">Medidas de socorro e de acolhimento de moradores de rua e outros grupos vulner\u00e1veis<\/li>\n<li style=\"font-weight: 400;\">Distribui\u00e7\u00e3o de 9 mil cestas b\u00e1sicas nos CRAS e no Centro dos Idosos<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Quadro de Apucarana \u00e9 equilibrado e Munic\u00edpio j\u00e1 prepara antecipadamente medidas para o p\u00f3s-pandemia<\/p>\n","protected":false},"author":4,"featured_media":36017,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-36011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/36011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=36011"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/36011\/revisions"}],"predecessor-version":[{"id":99342,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/36011\/revisions\/99342"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=36011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=36011"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=36011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}