{"id":35836,"date":"2020-08-03T18:34:19","date_gmt":"2020-08-03T21:34:19","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=35836"},"modified":"2024-10-08T09:21:59","modified_gmt":"2024-10-08T12:21:59","slug":"prefeitura-instala-totens-de-alcool-em-gel-em-pontos-estrategicos","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/prefeitura-instala-totens-de-alcool-em-gel-em-pontos-estrategicos\/","title":{"rendered":"Prefeitura instala totens de \u00e1lcool em gel em pontos estrat\u00e9gicos"},"content":{"rendered":"<p style=\"font-weight: 400;\">A prefeitura de Apucarana est\u00e1 instalando em pr\u00e9dios p\u00fablicos municipais totens com \u00e1lcool em gel 70%, que s\u00e3o acionados por um pedal na parte inferior do equipamento. O terminal do transporte coletivo urbano, a rodovi\u00e1ria e o Pronto Atendimento do Coronav\u00edrus foram os primeiros locais a contar com essa alternativa de higieniza\u00e7\u00e3o das m\u00e3os, que \u00e9 considerada uma das medidas mais efetivas para prevenir a contamina\u00e7\u00e3o da Covid-19.<\/p>\n<p style=\"font-weight: 400;\">O prefeito Junior da Femac informa que a prefeitura adquiriu 50 totens de \u00e1lcool em gel, com recursos da Autarquia Municipal de Sa\u00fade e da Secretaria da Assist\u00eancia Social. Dez unidades j\u00e1 chegaram e come\u00e7aram ser instaladas no \u00faltimo s\u00e1bado. Duas delas no terminal urbano, duas na rodovi\u00e1ria e duas no Pronto Atendimento do Coronav\u00edrus. \u201cOs outros quatro ir\u00e3o para o UPA e pr\u00e9dio da prefeitura\u201d, informa o prefeito.<\/p>\n<p style=\"font-weight: 400;\">A previs\u00e3o para chegada do restante dos totens \u00e9 para meados deste m\u00eas e ser\u00e3o instalados nos CRAS (Centro de Refer\u00eancia de Assist\u00eancia Social), capelas mortu\u00e1rias e em outros \u00f3rg\u00e3os municipais. \u201cTudo que est\u00e1 ao nosso alcance para refor\u00e7ar as medidas de enfrentamento da pandemia estamos fazendo. Distribu\u00edmos sab\u00e3o l\u00edquido, m\u00e1scaras\u00a0a todos os cidad\u00e3os e agora estamos instalando esses totens para que a popula\u00e7\u00e3o tenha mais essa alternativa na higieniza\u00e7\u00e3o das m\u00e3os\u201d, diz o prefeito que pede \u00e0 popula\u00e7\u00e3o para ajudar a cuidar desse equipamento importante neste momento de pandemia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Terminal urbano, rodovi\u00e1ria e Pronto Atendimento do Coronav\u00edrus j\u00e1 receberam o equipamento de higieniza\u00e7\u00e3o das m\u00e3os<\/p>\n","protected":false},"author":4,"featured_media":35837,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-35836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/35836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=35836"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/35836\/revisions"}],"predecessor-version":[{"id":59486,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/35836\/revisions\/59486"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=35836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=35836"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=35836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}