{"id":35608,"date":"2020-07-29T12:15:54","date_gmt":"2020-07-29T15:15:54","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=35608"},"modified":"2024-10-08T09:22:00","modified_gmt":"2024-10-08T12:22:00","slug":"prefeito-emite-nota-de-pesar-pela-morte-de-pioneira","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/prefeito-emite-nota-de-pesar-pela-morte-de-pioneira\/","title":{"rendered":"Prefeito emite nota de pesar pela morte de pioneira"},"content":{"rendered":"<p>O prefeito Junior da Femac manifestou hoje (29\/07) profundo pesar pelo falecimento da pioneira J\u00falia Mazurok, aos 86 anos. \u00a0\u201cA Dona J\u00falia Mazurok foi casada com o fot\u00f3grafo Dem\u00e9trio Mazurok, que trabalhou na Prefeitura de Apucarana entre as d\u00e9cadas de 80 e 90. Dona J\u00falia deixa enlutadas as filhas Eva, Maria, Nina, Nat\u00e1lia, Le\u00f4nida e Sim\u00e3o, al\u00e9m de netos e bisnetos. Dona J\u00falia \u00e9 de fam\u00edlia pioneira, integrante da Col\u00f4nia Ucraniana e, junto com o falecido marido, deu a sua contribui\u00e7\u00e3o no desenvolvimento de Apucarana\u201d, afirma Junior da Femac.<br \/>\nO vel\u00f3rio de Dona J\u00falia Mazurok ocorreu na capela mortu\u00e1ria central e o sepultamento estava previsto para as 12 horas, no Cemit\u00e9rio da Saudade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pioneira e integrante da Col\u00f4nia Ucraniana, J\u00falia Mazurok, faleceu hoje aos 86 anos.<\/p>\n","protected":false},"author":4,"featured_media":35609,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-35608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/35608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=35608"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/35608\/revisions"}],"predecessor-version":[{"id":99369,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/35608\/revisions\/99369"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=35608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=35608"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=35608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}