{"id":35156,"date":"2020-07-20T20:16:01","date_gmt":"2020-07-20T23:16:01","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=35156"},"modified":"2024-10-08T09:21:00","modified_gmt":"2024-10-08T12:21:00","slug":"duplicacao-entre-apucarana-e-maua-da-serra-esta-concluida","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/duplicacao-entre-apucarana-e-maua-da-serra-esta-concluida\/","title":{"rendered":"Duplica\u00e7\u00e3o entre Apucarana e Mau\u00e1 da Serra est\u00e1 conclu\u00edda"},"content":{"rendered":"<p>A duplica\u00e7\u00e3o da BR-376 (Rodovia do Caf\u00e9), no trecho de cerca de 60 quil\u00f4metros, entre Apucarana e Mau\u00e1 da Serra, passando por Calif\u00f3rnia e Maril\u00e2ndia do Sul est\u00e1 conclu\u00edda. A informa\u00e7\u00e3o foi dada nesta segunda-feira por representantes da Concession\u00e1ria RodoNorte. E, pela manh\u00e3, o prefeito de Apucarana percorreu o trecho at\u00e9 Mau\u00e1 da Serra, onde se encontrou com o colega prefeito Hermes Wicthoff. Juntos os dois observaram os trechos finais das obras de duplica\u00e7\u00e3o e comemoraram a conquista.<br \/>\n\u201cEssa duplica\u00e7\u00e3o \u00e9 hist\u00f3rica para todos os cidad\u00e3os de Apucarana e de todo o Vale do Iva\u00ed, ap\u00f3s d\u00e9cadas de sofrimento e de trag\u00e9dias na rodovia. E, especificamente, em rela\u00e7\u00e3o a n\u00f3s de Apucarana tem um valor ainda maior, por que no in\u00edcio da duplica\u00e7\u00e3o do trecho Ponta Grossa-Apucarana havia apenas a frente de trabalho que vinha do sul para o norte\u201d, lembrou Junior da Femac.<br \/>\nO prefeito relata que em mar\u00e7o de 2013 a abertura da frente de trabalho norte, a partir de Apucarana, foi garantida ap\u00f3s uma ampla mobiliza\u00e7\u00e3o liderada pelo ent\u00e3o prefeito Beto Preto e por ele. \u201cNa \u00e9poca, percorremos todas as cidades do Vale do Iva\u00ed da macrorregi\u00e3o norte obtendo a ades\u00e3o de todos os prefeitos da Amuvi e da Amepar, e tamb\u00e9m de lideran\u00e7as empresariais e do agroneg\u00f3cio, em reuni\u00f5es realizadas no Conselho de Desenvolvimento de Maring\u00e1 (Codem), e na Associa\u00e7\u00e3o Comercial e Industrial de Londrina (Acil)\u201d, recordou Junior da Femac.<br \/>\nSegundo o prefeito de Apucarana, ver esse trecho de rodovia duplicado agora, depois de seis anos de obras \u00e9 muito especial para todos da regi\u00e3o. \u201cA rodovia vai garantir melhor mobilidade e mais seguran\u00e7a no transporte de cargas e para todos os demais condutores na liga\u00e7\u00e3o do norte ao sul do Estado\u201d, assinala, reiterando que foi uma \u00e1rdua luta que encabe\u00e7ou ao lado de Beto Preto.<br \/>\nEm mar\u00e7o de 2013, no trecho entre Ponta Grossa e Apucarana, de 244 quil\u00f4metros, havia apenas 13 quil\u00f4metros j\u00e1 duplicados, na Serra do Cadeado, entre Mau\u00e1 da Serra e Ortigueira. Na \u00e9poca o Governo do Estado anunciou a obra de 231 quil\u00f4metros, incluindo o contorno em Apucarana. A ordem de servi\u00e7o para o in\u00edcio das obras aconteceu em Ponta Grossa. Por\u00e9m, apenas a frente sul iria come\u00e7ar de imediato, por que j\u00e1 existia o projeto executivo elaborado pela CCR Rodonorte.<br \/>\nAs obras de duplica\u00e7\u00e3o da Rodovia do Caf\u00e9 na frente norte, no trecho de Apucarana a Mau\u00e1 da Serra, foram iniciadas apenas em setembro de 2014. Na \u00e9poca, o prefeito Beto Preto e o vice, J\u00fanior da Femac, participaram do lan\u00e7amento da duplica\u00e7\u00e3o da BR-376, no trecho Apucarana a Calif\u00f3rnia. \u201cA ideia era ter uma segunda frente de obras no sentido norte-sul, como maneira de avan\u00e7ar mais r\u00e1pido na duplica\u00e7\u00e3o da Rodovia do Caf\u00e9\u201d, lembra Junior, avaliando que a obra ir\u00e1 gradativamente mudar o patamar da infraestrutura do Paran\u00e1, passando a dispor de um corredor de exporta\u00e7\u00e3o mais \u00e1gil e seguro, ligando a macrorregi\u00e3o norte com Curitiba e o Porto de Paranagu\u00e1.<br \/>\nA partir da pr\u00f3xima concess\u00e3o de rodovias no Paran\u00e1, prevista para 2021, ainda restar\u00e1 um trecho de cerca de 80 Km para ser duplicado entre Ponta Grossa e Ortigueira.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conquista foi comemorada por Junior da Femac que, ao lado de Beto Preto, participou da mobiliza\u00e7\u00e3o pela \u201cfrente Norte\u201d (Foto: PMA)<\/p>\n","protected":false},"author":4,"featured_media":35164,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-35156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/35156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=35156"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/35156\/revisions"}],"predecessor-version":[{"id":99398,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/35156\/revisions\/99398"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=35156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=35156"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=35156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}