{"id":29492,"date":"2020-01-30T12:18:40","date_gmt":"2020-01-30T14:18:40","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=29492"},"modified":"2024-10-08T09:20:31","modified_gmt":"2024-10-08T12:20:31","slug":"ano-letivo-comeca-na-proxima-semana-na-rede-municipal-de-apucarana","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/ano-letivo-comeca-na-proxima-semana-na-rede-municipal-de-apucarana\/","title":{"rendered":"Ano letivo come\u00e7a na pr\u00f3xima semana na rede municipal de Apucarana"},"content":{"rendered":"<p>A Autarquia de Educa\u00e7\u00e3o divulgou hoje (30\/1) os calend\u00e1rios que ser\u00e3o seguidos pelos centros infantis (CMEIs) e escolas da rede municipal no ano letivo de 2020. Os pais dos alunos e a comunidade podem conferi-los atrav\u00e9s do site da <a href=\"http:\/\/www.apucarana.pr.gov.br\/ame\/calendarios\/\">Prefeitura de Apucarana<\/a>.<br \/>\nO in\u00edcio das aulas ser\u00e1 na pr\u00f3xima quarta-feira (5\/2) para as crian\u00e7as dos CMEIs e na quinta-feira (6\/2) para os alunos das escolas. O planejamento das atividades letivas e a forma\u00e7\u00e3o continuada dos professores, assistentes infantis e demais servidores est\u00e1 previsto para o per\u00edodo de 3 a 5\/2. Orienta\u00e7\u00f5es importantes j\u00e1 foram repassadas ontem (29\/1) aos diretores e coordenadores das 60 unidades de ensino, em encontro realizado na sede da Associa\u00e7\u00e3o dos Funcion\u00e1rios P\u00fablicos Municipais de Apucarana (AFAP).<br \/>\nDe acordo com a secret\u00e1ria de educa\u00e7\u00e3o, Marli Fernandes, mais de 12 mil matr\u00edculas foram efetuadas at\u00e9 o momento na rede municipal de Apucarana. \u201cNeste ano, a gest\u00e3o Beto Preto e J\u00fanior da Femac investiu quase R$ 3 milh\u00f5es na compra de uniformes e materiais escolares para os alunos e de uniformes de trabalho e equipamentos de seguran\u00e7a (EPIs) para os profissionais da educa\u00e7\u00e3o. As entregas devem acontecer j\u00e1 nos primeiros dias de aula,\u201d garantiu.<br \/>\nO prefeito J\u00fanior da Femac participou ontem do encontro com os diretores e coordenadores escolares. \u201cN\u00f3s temos uma responsabilidade muito grande, que \u00e9 garantir educa\u00e7\u00e3o equitativa e de qualidade para todos os alunos da rede municipal. O futuro das crian\u00e7as e tamb\u00e9m da cidade depende do nosso comprometimento e dedica\u00e7\u00e3o. Eu conto com cada um de voc\u00eas,\u201d conclamou o gestor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O in\u00edcio das aulas ser\u00e1 na quarta-feira (5\/2) para as crian\u00e7as dos CMEIs e na quinta-feira (6\/2) para os alunos das Escolas Municipais<\/p>\n","protected":false},"author":4,"featured_media":29493,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-29492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/29492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=29492"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/29492\/revisions"}],"predecessor-version":[{"id":99802,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/29492\/revisions\/99802"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=29492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=29492"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=29492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}