{"id":2387,"date":"2014-11-27T17:53:59","date_gmt":"2014-11-27T17:53:59","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=2387"},"modified":"2024-10-08T09:09:40","modified_gmt":"2024-10-08T12:09:40","slug":"grupos-conviver-encerram-atividades-do-ano-com-festa","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/grupos-conviver-encerram-atividades-do-ano-com-festa\/","title":{"rendered":"Grupos Conviver encerram atividades do ano com festa"},"content":{"rendered":"<p><p><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\">Um evento festivo promovido hoje pela prefeitura, atrav\u00e9s da Secretaria Municipal da Assist\u00eancia Social, no Clube 28 de Janeiro, marcou o encerramento das atividades de 2014 dos grupos Conviver da Terceira Idade de Apucarana. A programa\u00e7\u00e3o incluiu sorteio de brindes, din&acirc;micas, atividades de alongamento, ora\u00e7\u00f5es, m\u00fasica, dan\u00e7a e lanche.<\/span><\/p>\n<p>Num balan\u00e7o das atividades envolvendo a popula\u00e7\u00e3o da terceira idade durante o ano, a secret\u00e1ria da Assist\u00eancia Social, M\u00e1rcia Regina de Sousa, comemora o crescimento dos grupos Conviver no per\u00edodo. &ldquo;Come\u00e7amos 2014 com 34 grupos e agora estamos com 39, chegando a 1,2 mil participantes. Inovamos tamb\u00e9m um fator bastante positivo. Os homens que de uma maneira geral ficavam a margem da programa\u00e7\u00e3o para pessoas da terceira idade come\u00e7aram a participar e hoje temos em torno 60 deles integrando os grupos&rdquo;, comemora M\u00e1rcia.<\/p>\n<p>A secret\u00e1ria destaca tamb\u00e9m que o programa voltado \u00e0 terceira idade do munic\u00edpio cumpriu tudo que foi proposto no in\u00edcio das atividades dos grupos Conviver, em fevereiro. &ldquo;Fornecemos material de qualidade para os trabalhos de artesanato; promovemos o concurso Miss Terceira Idade; foram realizados bailes todas as sextas-feiras no Clube da Sabedoria; passamos a ofertar atividade f\u00edsica aos interessados; al\u00e9m dos sucessivos eventos de valoriza\u00e7\u00e3o das pessoas da terceira idade dentro da sociedade&rdquo;, relata M\u00e1rcia.<\/p>\n<p>J\u00e1 para a retomada das atividades dos grupos Conviver, em fevereiro de 2015, M\u00e1rcia anuncia o in\u00edcio da oferta de cursos de computa\u00e7\u00e3o e aulas de nata\u00e7\u00e3o para terceira idade. &ldquo;Eles lan\u00e7aram essas reivindica\u00e7\u00f5es e vamos atender&rdquo;, afirma M\u00e1rcia. O prefeito Beto Preto lembra a abertura da administra\u00e7\u00e3o municipal em ouvir e atender interesses da popula\u00e7\u00e3o da terceira idade. &ldquo;Vejam a prefeitura como uma parceira e vamos melhorar cada vez mais o atendimento que todos voc\u00eas precisam e merecem&rdquo;, afirma Beto Preto.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evento foi marcado sorteio de brindes, din&acirc;micas, atividades de alongamento, ora&ccedil;&otilde;es, m&uacute;sica, dan&ccedil;a e lanche<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2387","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=2387"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2387\/revisions"}],"predecessor-version":[{"id":104493,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2387\/revisions\/104493"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=2387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=2387"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=2387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}