{"id":2371,"date":"2014-11-24T15:40:59","date_gmt":"2014-11-24T15:40:59","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=2371"},"modified":"2024-10-08T09:09:41","modified_gmt":"2024-10-08T12:09:41","slug":"lagoao-recebeu-feras-do-bmx-nacional","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/lagoao-recebeu-feras-do-bmx-nacional\/","title":{"rendered":"Lago\u00e3o recebeu feras do BMX nacional"},"content":{"rendered":"<p>Pelo segundo ano consecutivo, a pista de manobras do Complexo Esportivo Jos\u00e9 Ant&ocirc;nio Basso (Lago\u00e3o) recebeu as feras do bicicross.<\/p>\n<p>Com apoio da Secretaria de Esportes e Lazer da Prefeitura de Apucarana, aconteceu neste s\u00e1bado e domingo (22 e 23\/11), a 2\u00aa edi\u00e7\u00e3o do Circuito X &#8211; Tour Brazil de BMX, nas modalidades Street Park e Half Pipe.<\/p>\n<p>A competi\u00e7\u00e3o teve a participa\u00e7\u00e3o de atletas de n\u00edvel nacional e internacional do Paran\u00e1, Santa Catarina, Minas Gerais e S\u00e3o Paulo.<\/p>\n<p>O resultado da competi\u00e7\u00e3o ser\u00e1 divulgado em breve na fan page oficial:<a href=\"http:\/\/www.facebook.com\/XtourBrazilApucarana\">http:\/\/www.facebook.com\/XtourBrazilApucarana<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O resultado da competi&ccedil;&atilde;o ser&aacute; divulgado em breve na fan page oficial: http:\/\/www.facebook.com\/XtourBrazilApucarana<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2371","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=2371"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2371\/revisions"}],"predecessor-version":[{"id":104507,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2371\/revisions\/104507"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=2371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=2371"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=2371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}