{"id":2367,"date":"2014-11-24T10:45:59","date_gmt":"2014-11-24T10:45:59","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=2367"},"modified":"2024-10-08T09:09:41","modified_gmt":"2024-10-08T12:09:41","slug":"terceira-etapa-do-circuito-santo-trevisan-tem-participacao-de-231-corredores","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/terceira-etapa-do-circuito-santo-trevisan-tem-participacao-de-231-corredores\/","title":{"rendered":"Terceira etapa do Circuito Santo Trevisan tem participa\u00e7\u00e3o de 231 corredores"},"content":{"rendered":"<p><p>A Secretaria de Esportes e Lazer da Prefeitura de Apucarana promoveu neste domingo (23\/11), com largada em frente \u00e0 loja Athletic Sport, a terceira etapa do 1\u00ba Circuito de Corrida de Rua Santo Trevisan. A prova contou com a participa\u00e7\u00e3o de 231 corredores, oriundos de Apucarana e de diversos munic\u00edpios da regi\u00e3o. O prefeito de Apucarana, Beto Preto, prestigiou a competi\u00e7\u00e3o, que foi disputada em percursos de 5 e de 10 quil&ocirc;metros, nas categorias feminino e masculino. <\/p>\n<p>O Circuito de Corrida de Rua Santo Trevisan 2014 est\u00e1 na sua primeira edi\u00e7\u00e3o e \u00e9 uma homenagem ao pioneiro Santo Trevisan. Aos 82 anos, Santo Trevisan esteve presente na terceira etapa. De acordo com o secret\u00e1rio municipal de Esportes e Lazer, Paulo Aparecido Kisner (Paul\u00e3o), a premia\u00e7\u00e3o \u00e9 de trof\u00e9us e medalhas. &ldquo;Desde a primeira etapa, disputada no Jardim Ponta Grossa, o circuito bem atraindo um bom n\u00famero de competidores, lembrando que a pr\u00f3xima etapa ser\u00e1 disputada no dia 14 de dezembro, no entorno do Lago Jaboti&rdquo;, pontua Paul\u00e3o. <\/p>\n<\/p>\n<p><b><u>CLASSIFICA&Ccedil;&Atilde;O DA 3\u00aa ETAPA DO CIRCUITO SANTO TREVISAN<\/u><\/b><\/p>\n<p><b><u>Feminino (5 mil metros)<\/u><\/b><\/p>\n<p>1\u00aa &ndash; Cristiane Rodrigues de Almeida  Equipe Acorrecam de Campo Mour\u00e3o <\/p>\n<p>2\u00aa &ndash; Alessandro Rodrigues Gouv\u00eaa  Equipe P\u00e9 Vermelho &ndash; Apucarana <\/p>\n<p>3\u00aa &ndash; Renata Caroline Campideli Equipe P\u00e9 Vermelho &ndash; Apucarana<\/p>\n<p><b><u>Masculino (5 mil metros)<\/u><\/b><\/p>\n<p>1\u00ba &#8211; Diemison da Silva Cadonhoto Equipe Papa L\u00e9guas &#8211; Borrazopolis <\/p>\n<p>2\u00ba &#8211; Paulo Sergio da Silva Equipe Supermercado Tokio &ndash; Maril\u00e3ndia do Sul<\/p>\n<p>3\u00ba &#8211; Fabio Junior dos Santos Equipe Sec. de Esporte de Apucarana <\/p>\n<p><b><u>Feminino (10 mil metros)<\/u><\/b><\/p>\n<p>1\u00aa &ndash; Rosiane C. Bolonhezi Equipe P\u00e9 Vermelho &ndash; Apucarana<\/p>\n<p>2\u00aa &ndash; Patricia Fix Avulso &ndash; Apucarana<\/p>\n<p>3\u00aa &#8211; Simone de Barros Equipe P\u00e9 Vermelho &ndash; Apucarana<\/p>\n<p><b><u>Masculino (10 mil metros)<\/u><\/b><\/p>\n<p>1\u00ba &#8211; Adilson Souza Ferreira  Equipe Acorrecam de Campo Mour\u00e3o<\/p>\n<p>2\u00ba &#8211; Davi Vital da Silva Equipe Sec. de Esporte de Apucarana<\/p>\n<p>3\u00ba &#8211; Vanderley Soares   Equipe Supermercado Tokio &ndash; Maril&acirc;ndia do Sul<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A competi&ccedil;&atilde;o foi disputada em percursos de 5 e de 10 quil&ocirc;metros, nas categorias feminino e masculino<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2367","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=2367"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2367\/revisions"}],"predecessor-version":[{"id":104512,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2367\/revisions\/104512"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=2367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=2367"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=2367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}