{"id":2359,"date":"2014-11-20T15:15:00","date_gmt":"2014-11-20T15:15:00","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=2359"},"modified":"2024-10-08T09:09:42","modified_gmt":"2024-10-08T12:09:42","slug":"apucarana-recebe-circuito-tour-brazil-de-bmx","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/apucarana-recebe-circuito-tour-brazil-de-bmx\/","title":{"rendered":"Apucarana recebe circuito &#8220;Tour Brazil de BMX&#8221;"},"content":{"rendered":"<p><p><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\">Pelo segundo ano consecutivo, a pista de manobras do Complexo Esportivo Jos\u00e9 Ant&ocirc;nio Basso (Lago\u00e3o) recebe as feras do bicicross. Com apoio da Secretaria de Esportes e Lazer da Prefeitura de Apucarana, acontece neste s\u00e1bado e domingo (22 e 23\/11), a 2\u00aa edi\u00e7\u00e3o do Circuito X &#8211; Tour Brazil de BMX, nas modalidades Street Park e Half Pipe. &ldquo;A competi\u00e7\u00e3o ter\u00e1 a participa\u00e7\u00e3o de atletas de n\u00edvel nacional e internacional do Paran\u00e1, Santa Catarina, Minas Gerais e S\u00e3o Paulo&rdquo;, informa professor Paulo Aparecido Kisner (Paul\u00e3o), secret\u00e1rio municipal da pasta.<br \/><\/span><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\"><br \/>Na categoria profissional Half Pipe destaque para Anderson Queiroz (Dande), 10\u00ba colocado no mundial da Alemanha e 1\u00ba colocado no Jump Festival; Rafael Pennacchi (Rafinha), 14\u00ba colocado Jump Festival da Rede Globo; Jeferson Cear\u00e1, 4\u00ba colocado Jump Festival; e Thiago Bernardo, 2\u00ba colocado no Pro Rad (Prog Radical da Globo).<br \/><\/span><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\"><br \/>O cronograma completo dos dois dias de competi\u00e7\u00e3o pode ser conferido na rede social da competi\u00e7\u00e3o: <\/span><a href=\"http:\/\/www.facebook.com\/XtourBrazilApucarana\" style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\">http:\/\/www.facebook.com\/XtourBrazilApucarana<\/a><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\">, Ou ainda com Rafael Pennacchi, organizador do evento, pelo celular (43) 9826-1428, ou na Secretaria Municipal de Esportes e Lazer, pelo 3422-5184.<\/span><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O cronograma completo dos dois dias de competi&ccedil;&atilde;o pode ser conferido na rede social da competi&ccedil;&atilde;o: http:\/\/www.facebook.com\/XtourBrazilApucarana<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2359","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=2359"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2359\/revisions"}],"predecessor-version":[{"id":104518,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2359\/revisions\/104518"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=2359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=2359"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=2359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}