{"id":2357,"date":"2014-11-19T17:55:00","date_gmt":"2014-11-19T17:55:00","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=2357"},"modified":"2024-10-08T09:09:42","modified_gmt":"2024-10-08T12:09:42","slug":"ame-conquista-o-curso-profuncionario-para-servidores-da-educacao","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/ame-conquista-o-curso-profuncionario-para-servidores-da-educacao\/","title":{"rendered":"AME conquista o curso Profuncion\u00e1rio para servidores da educa\u00e7\u00e3o"},"content":{"rendered":"<p><p><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\">A Autarquia Municipal de Educa\u00e7\u00e3o ir\u00e1 ofertar aos seus servidores, a partir de 2015, o curso T\u00e9cnico em Multimeios Did\u00e1ticos &ndash; Subsequente, do Programa de Forma\u00e7\u00e3o Inicial em Servi\u00e7o dos Profissionais da Educa\u00e7\u00e3o B\u00e1sica (Profuncion\u00e1rio). O an\u00fancio foi feito na tarde desta quarta-feira (19\/11), pelo prefeito Beto Preto e a diretora-presidente da AME, professora Marli Regina Fernandes da Silva.<br \/><\/span><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\"><br \/>Tamb\u00e9m estiveram presentes no ato, o secret\u00e1rio municipal de Ensino Superior, Fernando Jos\u00e9 de Freitas, a coordenadora do polo Apucarana da Universidade Aberta do Brasil (UAB), Sueli Gomes, e a coordenadora municipal do Instituto Federal do Paran\u00e1 (IFPR), Gislaine Andrade Ockner.<br \/><\/span><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\"><br \/>O Profuncion\u00e1rio \u00e9 uma a\u00e7\u00e3o do Minist\u00e9rio da Educa\u00e7\u00e3o que, atrav\u00e9s da Rede E-Tec Brasil, investe na forma\u00e7\u00e3o e na qualifica\u00e7\u00e3o dos profissionais que atuam em escolas p\u00fablicas de todo o pa\u00eds. No nosso estado, o programa j\u00e1 foi adotado h\u00e1 alguns anos, sendo que os cursos s\u00e3o ministrados pelo IFPR.<br \/><\/span><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\"><br \/>Segundo a professora Marli, nesse primeiro momento, a AME ofertar\u00e1 apenas a habilita\u00e7\u00e3o T\u00e9cnico em Multimeios Did\u00e1ticos &ndash; Subsequente, que tem como p\u00fablico alvo os assistentes administrativos das institui\u00e7\u00f5es municipais de ensino. &ldquo;Mas n\u00f3s j\u00e1 estamos pleiteando junto ao IFPR a implanta\u00e7\u00e3o de outras modalidades que contemplem tamb\u00e9m os auxiliares de servi\u00e7os gerais e as merendeiras das escolas&rdquo;, disse<br \/><\/span><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\"><br \/>O prefeito Beto Preto, por sua vez, destacou o pioneirismo da AME em ampliar a iniciativa, que j\u00e1 existe na rede estadual, tamb\u00e9m para os seus servidores. &ldquo;Apucarana ser\u00e1 uma das primeiras cidades do Paran\u00e1 a expandir essa forma\u00e7\u00e3o continuada tamb\u00e9m para os funcion\u00e1rios municipais&rdquo;, afirmou.<br \/><\/span><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\"><br \/>O curso T\u00e9cnico em Multimeios Did\u00e1ticos &ndash; Subsequente, totalmente gratuito, tem dura\u00e7\u00e3o de dois anos e ser\u00e1 realizado na modalidade \u00e0 dist&acirc;ncia, com aulas presenciais apenas uma vez por semana no polo da Universidade Aberta do Brasil (UAB).<br \/><\/span><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\"><br \/>As inscri\u00e7\u00f5es, limitadas a 30 vagas, poder\u00e3o ser feitas de 20 a 26 de novembro no blog do polo UAB atrav\u00e9s do link<\/span><a href=\"http:\/\/goo.gl\/forms\/YDJxN4tQap\" style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\">HTTP:\/\/goo.gl\/forms\/YDJxN4tQap<\/a><span style=\"letter-spacing: -0.02em; line-height: 1.45em; background-color: initial;\">. Para a inscri\u00e7\u00e3o, \u00e9 necess\u00e1rio que o candidato comprove ser servidor efetivo da educa\u00e7\u00e3o que exer\u00e7a fun\u00e7\u00e3o compat\u00edvel a assistente administrativo e possuir o ensino m\u00e9dio completo. <\/span><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesse primeiro momento, a AME ofertar&aacute; apenas a habilita&ccedil;&atilde;o T&eacute;cnico em Multimeios Did&aacute;ticos &ndash; Subsequente<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2357","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=2357"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2357\/revisions"}],"predecessor-version":[{"id":104522,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2357\/revisions\/104522"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=2357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=2357"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=2357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}