{"id":2340,"date":"2014-11-14T13:25:59","date_gmt":"2014-11-14T13:25:59","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=2340"},"modified":"2024-10-08T09:09:43","modified_gmt":"2024-10-08T12:09:43","slug":"escolas-e-cmeis-municipais-abrem-periodo-de-matriculas","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/escolas-e-cmeis-municipais-abrem-periodo-de-matriculas\/","title":{"rendered":"Escolas e CMEIs municipais abrem per\u00edodo de matr\u00edculas"},"content":{"rendered":"<p><p>A Autarquia Municipal de Educa\u00e7\u00e3o (AME) comunica que abrir\u00e1, na pr\u00f3xima semana, o per\u00edodo de matr\u00edculas para o ano letivo 2015. As vagas s\u00e3o para a Educa\u00e7\u00e3o Infantil, o Ensino Fundamental e a Educa\u00e7\u00e3o de Jovens e Adultos (EJA). <\/p>\n<p>Os interessados devem comparecer, de 17 a 21 de novembro, \u00e0 escola ou CMEI mais pr\u00f3ximo de sua casa. Os documentos necess\u00e1rios para a matr\u00edcula das crian\u00e7as s\u00e3o certid\u00e3o de nascimento, carteirinha de vacina\u00e7\u00e3o, conta de luz atualizada e documento de identifica\u00e7\u00e3o (RG) de pelo menos um dos pais. J\u00e1 para os adultos s\u00e3o exigidos apenas o comprovante de resid\u00eancia e o documento de identifica\u00e7\u00e3o com foto.<\/p>\n<p>Unicamente para as fam\u00edlias dos Residenciais Ja\u00e7an\u00e3 e Sumatra I e II e, a AME oferecer\u00e1 um cronograma diferenciado de matr\u00edculas. <\/p>\n<p><b>Residenciais Sumatra I e Ja\u00e7an\u00e3 &ndash;<\/b> Os moradores desses dois bairros ser\u00e3o atendidos no s\u00e1bado (22\/11), das 8 \u00e0s 12 horas, na sede da nova escola, localizada \u00e0 Avenida Magno Cavalcanti Cerqueira, s\/n.<\/p>\n<p><b>Residencial Sumatra II &ndash;<\/b> J\u00e1 os futuros moradores dessa comunidade poder\u00e3o realizar as matr\u00edculas na mesma ocasi\u00e3o em que assinar\u00e3o seus contratos habitacionais com a Caixa Econ&ocirc;mica Federal, nos dias 19 e 20 de novembro, no gin\u00e1sio de esportes do SESI, situado na Avenida Avia\u00e7\u00e3o, 1851 &ndash; Jardim Aeroporto. <\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As matr&iacute;culas para a Educa&ccedil;&atilde;o Infantil, Ensino Fundamental e EJA ser&atilde;o feitas de 17 a 21 de novembro na rede municipal de ensino.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2340","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=2340"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2340\/revisions"}],"predecessor-version":[{"id":104539,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2340\/revisions\/104539"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=2340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=2340"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=2340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}