{"id":2327,"date":"2014-11-12T10:18:59","date_gmt":"2014-11-12T10:18:59","guid":{"rendered":"http:\/\/172.16.0.7\/site-antigo\/?p=2327"},"modified":"2024-10-08T09:09:43","modified_gmt":"2024-10-08T12:09:43","slug":"programa-jovens-empreendedores-homenageia-professores-apucaranenses","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/programa-jovens-empreendedores-homenageia-professores-apucaranenses\/","title":{"rendered":"Programa Jovens Empreendedores homenageia professores apucaranenses"},"content":{"rendered":"<p><p>A diretora-presidente da AME, professora Marli Regina Fernandes da Silva, e outras 34 educadoras da rede municipal de ensino participaram, na \u00faltima sexta-feira (07\/11), em Londrina, da cerim&ocirc;nia de encerramento do Programa Jovens Empreendedores Primeiros Passos (JEPPs). Na ocasi\u00e3o, elas foram homenageadas pelo Sebrae\/Pr com o recebimento de placas em reconhecimento pela implanta\u00e7\u00e3o da Educa\u00e7\u00e3o Empreendedora no Munic\u00edpio.<\/p>\n<p>Em 2014, a AME aderiu ao JEPPs e o ofertou a todos os alunos do 2\u00ba ano de 33 escolas. Por meio dele, as crian\u00e7as puderam aprender no\u00e7\u00f5es de cooperativismo, protagonismo juvenil, ecossustentabilidade, \u00e9tica e cidadania, entre outros assuntos.<\/p>\n<p>Os t\u00f3picos foram inseridos em sala de aula sob o tema &ldquo;Ervas Arom\u00e1ticas e Temperos Naturais&rdquo;, por meio do qual os estudantes ainda foram convidados a refletir sobre a import&acirc;ncia de se manter uma alimenta\u00e7\u00e3o saud\u00e1vel e como funcionam o plantio, o cultivo e a revenda de mudas. At\u00e9 dezembro, os temperos obtidos ser\u00e3o comercializados em feiras de empreendedorismo organizadas nas pr\u00f3prias institui\u00e7\u00f5es.<\/p>\n<p>Como parte da forma\u00e7\u00e3o continuada oferecida aos envolvidos no JEPPs, as educadoras da AME tamb\u00e9m assistiram, na \u00faltima sexta, por meio de teleconfer\u00eancia, a uma palestra com o professor Louis Jacques Filion, da Universidade de Montreal, no Canad\u00e1, que \u00e9 considerado o &ldquo;pai do empreendedorismo&rdquo; no mundo.<\/p>\n<p>De acordo com a professora Marli, a Autarquia Municipal de Educa\u00e7\u00e3o pretende renovar e ampliar a parceria com Sebrae\/Pr para o ano que vem. &ldquo;Projetos como esse s\u00e3o sempre bem vindos, pois eles v\u00eam ao encontro do curr\u00edculo que estruturamos e agregam valor ao ensino ofertado pelas nossas escolas&rdquo;, disse. <\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A diretora-presidente da AME e outras 34 docentes receberam placas, do Sebrae\/Pr em reconhecimento pela implanta&ccedil;&atilde;o da Educa&ccedil;&atilde;o Empreendedora no Munic&iacute;pio <\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2327","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=2327"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2327\/revisions"}],"predecessor-version":[{"id":104552,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/2327\/revisions\/104552"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=2327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=2327"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=2327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}