{"id":127362,"date":"2026-05-28T14:28:15","date_gmt":"2026-05-28T17:28:15","guid":{"rendered":"https:\/\/www.apucarana.pr.gov.br\/site\/?p=127362"},"modified":"2026-05-29T12:24:20","modified_gmt":"2026-05-29T15:24:20","slug":"teatro-de-fantoches-orienta-criancas-sobre-prevencao-ao-abuso-infantil-nas-escolas-municipais","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/teatro-de-fantoches-orienta-criancas-sobre-prevencao-ao-abuso-infantil-nas-escolas-municipais\/","title":{"rendered":"Teatro de fantoches orienta crian\u00e7as sobre preven\u00e7\u00e3o ao abuso infantil nas escolas municipais"},"content":{"rendered":"\n\t\t<!-- MasterSlider -->\n\t\t<div id=\"P_MS6a5767b95133a\" class=\"master-slider-parent master-slider-gallery   ms-parent-id-0\" style=\"\" >\n\n\t\t\t\n\t\t\t<!-- MasterSlider Main -->\n\t\t\t<div id=\"MS6a5767b95133a\" class=\"master-slider ms-skin-default\" >\n\t\t\t\t \t\t\t\t \n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"2026-05-28_fantoches_escola_012\" title=\"2026-05-28_fantoches_escola_012\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_012-1024x576.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_012-1024x576.jpg\" target=\"_self\"    >2026-05-28_fantoches_escola_012<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_012-1024x576-140x80.jpg\" alt=\"2026-05-28_fantoches_escola_012\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"2026-05-28_fantoches_escola_011\" title=\"2026-05-28_fantoches_escola_011\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_011-1024x576.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_011-1024x576.jpg\" target=\"_self\"    >2026-05-28_fantoches_escola_011<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_011-1024x576-140x80.jpg\" alt=\"2026-05-28_fantoches_escola_011\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"2026-05-28_fantoches_escola_010\" title=\"2026-05-28_fantoches_escola_010\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_010-1024x576.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_010-1024x576.jpg\" target=\"_self\"    >2026-05-28_fantoches_escola_010<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_010-1024x576-140x80.jpg\" alt=\"2026-05-28_fantoches_escola_010\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"2026-05-28_fantoches_escola_009\" title=\"2026-05-28_fantoches_escola_009\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_009-1024x576.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_009-1024x576.jpg\" target=\"_self\"    >2026-05-28_fantoches_escola_009<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_009-1024x576-140x80.jpg\" alt=\"2026-05-28_fantoches_escola_009\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"2026-05-28_fantoches_escola_008\" title=\"2026-05-28_fantoches_escola_008\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_008-1024x576.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_008-1024x576.jpg\" target=\"_self\"    >2026-05-28_fantoches_escola_008<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_008-1024x576-140x80.jpg\" alt=\"2026-05-28_fantoches_escola_008\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"2026-05-28_fantoches_escola_003\" title=\"2026-05-28_fantoches_escola_003\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_003-1024x576.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_003-1024x576.jpg\" target=\"_self\"    >2026-05-28_fantoches_escola_003<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_003-1024x576-140x80.jpg\" alt=\"2026-05-28_fantoches_escola_003\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"2026-05-28_fantoches_escola_004\" title=\"2026-05-28_fantoches_escola_004\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_004-1024x576.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_004-1024x576.jpg\" target=\"_self\"    >2026-05-28_fantoches_escola_004<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_004-1024x576-140x80.jpg\" alt=\"2026-05-28_fantoches_escola_004\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"2026-05-28_fantoches_escola_005\" title=\"2026-05-28_fantoches_escola_005\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_005-1024x576.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_005-1024x576.jpg\" target=\"_self\"    >2026-05-28_fantoches_escola_005<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_005-1024x576-140x80.jpg\" alt=\"2026-05-28_fantoches_escola_005\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"2026-05-28_fantoches_escola_006\" title=\"2026-05-28_fantoches_escola_006\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_006-1024x576.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_006-1024x576.jpg\" target=\"_self\"    >2026-05-28_fantoches_escola_006<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_006-1024x576-140x80.jpg\" alt=\"2026-05-28_fantoches_escola_006\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"2026-05-28_fantoches_escola_007\" title=\"2026-05-28_fantoches_escola_007\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_007-1024x576.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_007-1024x576.jpg\" target=\"_self\"    >2026-05-28_fantoches_escola_007<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_007-1024x576-140x80.jpg\" alt=\"2026-05-28_fantoches_escola_007\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"2026-05-28_fantoches_escola_002\" title=\"2026-05-28_fantoches_escola_002\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_002-1024x576.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_002-1024x576.jpg\" target=\"_self\"    >2026-05-28_fantoches_escola_002<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_002-1024x576-140x80.jpg\" alt=\"2026-05-28_fantoches_escola_002\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"2026-05-28_fantoches_escola_001\" title=\"2026-05-28_fantoches_escola_001\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_001-1024x576.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_001-1024x576.jpg\" target=\"_self\"    >2026-05-28_fantoches_escola_001<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/2026-05-28_fantoches_escola_001-1024x576-140x80.jpg\" alt=\"2026-05-28_fantoches_escola_001\" \/>\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t<!-- END MasterSlider Main -->\n\n\t\t\t \n\t\t<\/div>\n\t\t<!-- END MasterSlider -->\n\n\t\t<script>\n\t\t( window.MSReady = window.MSReady || [] ).push( function( $ ) {\n\n\t\t\t\"use strict\";\n\t\t\tvar masterslider_133a = new MasterSlider();\n\n\t\t\t\/\/ slider controls\n\t\t\tmasterslider_133a.control('arrows'     ,{ autohide:true, overVideo:true  });\n\t\t\tmasterslider_133a.control('thumblist'  ,{ autohide:false, overVideo:true, dir:'h', speed:17, inset:false, arrows:false, hover:false, customClass:'', align:'bottom',type:'thumbs', margin:2, width:140, height:80, space:2, fillMode:'fill'  });\n\t\t\t\/\/ slider setup\n\t\t\tmasterslider_133a.setup(\"MS6a5767b95133a\", {\n\t\t\t\twidth           : 960,\n\t\t\t\theight          : 540,\n\t\t\t\tminHeight       : 0,\n\t\t\t\tspace           : 0,\n\t\t\t\tstart           : 1,\n\t\t\t\tgrabCursor      : true,\n\t\t\t\tswipe           : true,\n\t\t\t\tmouse           : true,\n\t\t\t\tkeyboard        : false,\n\t\t\t\tlayout          : \"fillwidth\",\n\t\t\t\twheel           : false,\n\t\t\t\tautoplay        : true,\n                instantStartLayers:false,\n\t\t\t\tmobileBGVideo:false,\n\t\t\t\tloop            : true,\n\t\t\t\tshuffle         : false,\n\t\t\t\tpreload         : 3,\n\t\t\t\theightLimit     : false,\n\t\t\t\tautoHeight      : false,\n\t\t\t\tsmoothHeight    : true,\n\t\t\t\tendPause        : false,\n\t\t\t\toverPause       : false,\n\t\t\t\tfillMode        : \"fill\",\n\t\t\t\tcenterControls  : true,\n\t\t\t\tstartOnAppear   : false,\n\t\t\t\tlayersMode      : \"center\",\n\t\t\t\tautofillTarget  : \"\",\n\t\t\t\thideLayers      : false,\n\t\t\t\tfullscreenMargin: 0,\n\t\t\t\tspeed           : 17,\n\t\t\t\tdir             : \"h\",\n\t\t\t\tresponsive      : true,\n\t\t\t\ttabletWidth     : 768,\n\t\t\t\ttabletHeight    : null,\n\t\t\t\tphoneWidth      : 480,\n\t\t\t\tphoneHeight    : null,\n\t\t\t\tsizingReference : window,\n\t\t\t\tparallaxMode    : 'swipe',\n\t\t\t\tview            : \"basic\"\n\t\t\t});\n\n\t\t\t\n\t\t\twindow.masterslider_instances = window.masterslider_instances || [];\n\t\t\twindow.masterslider_instances.push( masterslider_133a );\n\t\t});\n\t\t<\/script>\n\n\n<p>A Prefeitura de Apucarana est\u00e1 levando orienta\u00e7\u00f5es sobre preven\u00e7\u00e3o ao abuso infantil para dentro das escolas municipais de forma l\u00fadica, acess\u00edvel e adequada \u00e0 faixa et\u00e1ria dos estudantes. A conscientiza\u00e7\u00e3o, realizada por meio de um teatro de fantoches voltado a crian\u00e7as de 6 a 10 anos, \u00e9 coordenada pela Secretaria da Mulher e Assuntos da Fam\u00edlia (SEMAF) e integra a programa\u00e7\u00e3o da campanha Maio Laranja.<\/p>\n<p>A secret\u00e1ria da Mulher e Assuntos da Fam\u00edlia, Karine Mota, destaca que o trabalho preventivo fortalece a rede de prote\u00e7\u00e3o e aproxima os estudantes de orienta\u00e7\u00f5es importantes. \u201c\u00c9 fundamental que nossas crian\u00e7as saibam identificar situa\u00e7\u00f5es de risco e, principalmente, que se sintam seguras para conversar com adultos de sua confian\u00e7a sobre qualquer coisa que as incomode. O teatro de fantoches \u00e9 uma ferramenta poderosa para abordar um tema t\u00e3o delicado de maneira did\u00e1tica e eficaz\u201d, ressaltou.<\/p>\n<p>Karine Mota tamb\u00e9m refor\u00e7ou que a atua\u00e7\u00e3o integrada entre as secretarias municipais \u00e9 um diferencial da iniciativa. \u201cO teatro de fantoches \u00e9 uma atividade que envolve as secretarias da Mulher, Assist\u00eancia Social e Educa\u00e7\u00e3o. Quando a rede de prote\u00e7\u00e3o atua de forma articulada, conseguimos chegar com muito mais efetividade at\u00e9 as crian\u00e7as e suas fam\u00edlias\u201d, afirmou.<\/p>\n<p>A diretora do Centro de Atendimento \u00e0 Mulher (CAM), a advogada Fernanda de Freitas Ara\u00fajo, explica que o teatro conta a hist\u00f3ria de uma tartaruga em um cen\u00e1rio tem\u00e1tico do fundo do mar. \u201cDe forma l\u00fadica, a narrativa mostra a import\u00e2ncia de n\u00e3o guardar segredos e de procurar um adulto de confian\u00e7a diante de qualquer situa\u00e7\u00e3o que cause medo, desconforto ou inseguran\u00e7a\u201d, explicou.<\/p>\n<p>Durante a apresenta\u00e7\u00e3o, a tartaruga \u00e9 abordada por um polvo adulto, que a convida para sua casa, oferece doces e tenta tirar fotos dela sem o casco. A cena ajuda as crian\u00e7as a reconhecer comportamentos inadequados e a compreender a import\u00e2ncia de pedir ajuda.<\/p>\n<p>As apresenta\u00e7\u00f5es j\u00e1 foram realizadas na Escola Municipal Fernando Jos\u00e9 Acosta, no Residencial Sumatra, e na Escola Municipal Luiz Carlos Prestes, no Jardim Am\u00e9rica. Dentro do cronograma, a atividade tamb\u00e9m acontece nesta quinta-feira na Escola Municipal Monsenhor Arnaldo Beltrami, no Jardim Colonial, e na Escola Municipal Maria Tereza Gebrim, no Residencial Fariz Gebrim.<\/p>\n<p>A programa\u00e7\u00e3o do Maio Laranja em Apucarana come\u00e7ou no dia 18, com blitz educativa na Pra\u00e7a Rui Barbosa, distribui\u00e7\u00e3o de materiais informativos e orienta\u00e7\u00f5es sobre canais de den\u00fancia. Tamb\u00e9m foram promovidas apresenta\u00e7\u00f5es do Circo Teatro Sem Lona, no Cine Teatro F\u00eanix, debates com profissionais da rede de prote\u00e7\u00e3o e atividades voltadas \u00e0s fam\u00edlias.<\/p>\n<p>O encerramento da programa\u00e7\u00e3o prev\u00ea ainda, nesta quinta-feira, palestras no audit\u00f3rio Jos\u00e9 Berton, na Unespar. A campanha em Apucarana \u00e9 promovida pela Secretaria Municipal de Assist\u00eancia Social e pelo Conselho Municipal dos Direitos da Crian\u00e7a e do Adolescente (CMDCA), com apoio de diversos \u00f3rg\u00e3os da rede de prote\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Apucarana est&aacute; levando orienta&ccedil;&otilde;es sobre preven&ccedil;&atilde;o ao abuso infantil para dentro das escolas municipais de forma l&uacute;dica, acess&iacute;vel e adequada &agrave; faixa et&aacute;ria dos estudantes. A conscientiza&ccedil;&atilde;o, realizada por meio de um teatro de fantoches voltado a crian&ccedil;as de 6 a 10 anos, &eacute; coordenada pela Secretaria da Mulher e Assuntos da [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":127372,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-127362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/127362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=127362"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/127362\/revisions"}],"predecessor-version":[{"id":127375,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/127362\/revisions\/127375"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media\/127372"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=127362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=127362"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=127362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}