{"id":127249,"date":"2026-05-25T19:15:05","date_gmt":"2026-05-25T22:15:05","guid":{"rendered":"https:\/\/www.apucarana.pr.gov.br\/site\/?p=127249"},"modified":"2026-05-26T13:57:26","modified_gmt":"2026-05-26T16:57:26","slug":"prefeitura-de-apucarana-apresenta-novo-modelo-de-gestao-e-organizacao-para-feira-do-produtor-rural","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/prefeitura-de-apucarana-apresenta-novo-modelo-de-gestao-e-organizacao-para-feira-do-produtor-rural\/","title":{"rendered":"Prefeitura de Apucarana apresenta novo modelo de gest\u00e3o e organiza\u00e7\u00e3o para Feira do Produtor Rural"},"content":{"rendered":"\n\t\t<!-- MasterSlider -->\n\t\t<div id=\"P_MS6a5778fb790a1\" class=\"master-slider-parent master-slider-gallery   ms-parent-id-0\" style=\"\" >\n\n\t\t\t\n\t\t\t<!-- MasterSlider Main -->\n\t\t\t<div id=\"MS6a5778fb790a1\" class=\"master-slider ms-skin-default\" >\n\t\t\t\t \t\t\t\t \n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"25-05-2026_reuniao_feirantes01\" title=\"25-05-2026_reuniao_feirantes01\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-1024x683.jpg\" target=\"_self\"    >25-05-2026_reuniao_feirantes01<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-1024x683-140x80.jpg\" alt=\"25-05-2026_reuniao_feirantes01\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"25-05-2026_reuniao_feirantes01-2\" title=\"25-05-2026_reuniao_feirantes01-2\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-2-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-2-1024x683.jpg\" target=\"_self\"    >25-05-2026_reuniao_feirantes01-2<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-2-1024x683-140x80.jpg\" alt=\"25-05-2026_reuniao_feirantes01-2\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"25-05-2026_reuniao_feirantes01-4\" title=\"25-05-2026_reuniao_feirantes01-4\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-4-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-4-1024x683.jpg\" target=\"_self\"    >25-05-2026_reuniao_feirantes01-4<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-4-1024x683-140x80.jpg\" alt=\"25-05-2026_reuniao_feirantes01-4\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"25-05-2026_reuniao_feirantes01-6\" title=\"25-05-2026_reuniao_feirantes01-6\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-6-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-6-1024x683.jpg\" target=\"_self\"    >25-05-2026_reuniao_feirantes01-6<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-6-1024x683-140x80.jpg\" alt=\"25-05-2026_reuniao_feirantes01-6\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"25-05-2026_reuniao_feirantes01-9\" title=\"25-05-2026_reuniao_feirantes01-9\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-9-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-9-1024x683.jpg\" target=\"_self\"    >25-05-2026_reuniao_feirantes01-9<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-9-1024x683-140x80.jpg\" alt=\"25-05-2026_reuniao_feirantes01-9\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"25-05-2026_reuniao_feirantes01-11\" title=\"25-05-2026_reuniao_feirantes01-11\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-11-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-11-1024x683.jpg\" target=\"_self\"    >25-05-2026_reuniao_feirantes01-11<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-11-1024x683-140x80.jpg\" alt=\"25-05-2026_reuniao_feirantes01-11\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"25-05-2026_reuniao_feirantes01-14\" title=\"25-05-2026_reuniao_feirantes01-14\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-14-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-14-1024x683.jpg\" target=\"_self\"    >25-05-2026_reuniao_feirantes01-14<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-14-1024x683-140x80.jpg\" alt=\"25-05-2026_reuniao_feirantes01-14\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"25-05-2026_reuniao_feirantes01-16\" title=\"25-05-2026_reuniao_feirantes01-16\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-16-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-16-1024x683.jpg\" target=\"_self\"    >25-05-2026_reuniao_feirantes01-16<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-16-1024x683-140x80.jpg\" alt=\"25-05-2026_reuniao_feirantes01-16\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"25-05-2026_reuniao_feirantes01-18\" title=\"25-05-2026_reuniao_feirantes01-18\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-18-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-18-1024x683.jpg\" target=\"_self\"    >25-05-2026_reuniao_feirantes01-18<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-18-1024x683-140x80.jpg\" alt=\"25-05-2026_reuniao_feirantes01-18\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"25-05-2026_reuniao_feirantes01-20\" title=\"25-05-2026_reuniao_feirantes01-20\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-20-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-20-1024x683.jpg\" target=\"_self\"    >25-05-2026_reuniao_feirantes01-20<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-20-1024x683-140x80.jpg\" alt=\"25-05-2026_reuniao_feirantes01-20\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"25-05-2026_reuniao_feirantes01-22\" title=\"25-05-2026_reuniao_feirantes01-22\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-22-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-22-1024x683.jpg\" target=\"_self\"    >25-05-2026_reuniao_feirantes01-22<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2026\/05\/25-05-2026_reuniao_feirantes01-22-1024x683-140x80.jpg\" alt=\"25-05-2026_reuniao_feirantes01-22\" \/>\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t<!-- END MasterSlider Main -->\n\n\t\t\t \n\t\t<\/div>\n\t\t<!-- END MasterSlider -->\n\n\t\t<script>\n\t\t( window.MSReady = window.MSReady || [] ).push( function( $ ) {\n\n\t\t\t\"use strict\";\n\t\t\tvar masterslider_90a1 = new MasterSlider();\n\n\t\t\t\/\/ slider controls\n\t\t\tmasterslider_90a1.control('arrows'     ,{ autohide:true, overVideo:true  });\n\t\t\tmasterslider_90a1.control('thumblist'  ,{ autohide:false, overVideo:true, dir:'h', speed:17, inset:false, arrows:false, hover:false, customClass:'', align:'bottom',type:'thumbs', margin:2, width:140, height:80, space:2, fillMode:'fill'  });\n\t\t\t\/\/ slider setup\n\t\t\tmasterslider_90a1.setup(\"MS6a5778fb790a1\", {\n\t\t\t\twidth           : 960,\n\t\t\t\theight          : 540,\n\t\t\t\tminHeight       : 0,\n\t\t\t\tspace           : 0,\n\t\t\t\tstart           : 1,\n\t\t\t\tgrabCursor      : true,\n\t\t\t\tswipe           : true,\n\t\t\t\tmouse           : true,\n\t\t\t\tkeyboard        : false,\n\t\t\t\tlayout          : \"fillwidth\",\n\t\t\t\twheel           : false,\n\t\t\t\tautoplay        : true,\n                instantStartLayers:false,\n\t\t\t\tmobileBGVideo:false,\n\t\t\t\tloop            : true,\n\t\t\t\tshuffle         : false,\n\t\t\t\tpreload         : 3,\n\t\t\t\theightLimit     : false,\n\t\t\t\tautoHeight      : false,\n\t\t\t\tsmoothHeight    : true,\n\t\t\t\tendPause        : false,\n\t\t\t\toverPause       : false,\n\t\t\t\tfillMode        : \"fill\",\n\t\t\t\tcenterControls  : true,\n\t\t\t\tstartOnAppear   : false,\n\t\t\t\tlayersMode      : \"center\",\n\t\t\t\tautofillTarget  : \"\",\n\t\t\t\thideLayers      : false,\n\t\t\t\tfullscreenMargin: 0,\n\t\t\t\tspeed           : 17,\n\t\t\t\tdir             : \"h\",\n\t\t\t\tresponsive      : true,\n\t\t\t\ttabletWidth     : 768,\n\t\t\t\ttabletHeight    : null,\n\t\t\t\tphoneWidth      : 480,\n\t\t\t\tphoneHeight    : null,\n\t\t\t\tsizingReference : window,\n\t\t\t\tparallaxMode    : 'swipe',\n\t\t\t\tview            : \"basic\"\n\t\t\t});\n\n\t\t\t\n\t\t\twindow.masterslider_instances = window.masterslider_instances || [];\n\t\t\twindow.masterslider_instances.push( masterslider_90a1 );\n\t\t});\n\t\t<\/script>\n\n\n<p>Agricultores familiares que integram a tradicional Feira do Produtor Rural de Apucarana participaram nesta segunda-feira (25\/05), no sal\u00e3o nobre da prefeitura, de uma reuni\u00e3o com t\u00e9cnicos da Secretaria Municipal da Agricultura. Al\u00e9m do repasse de informa\u00e7\u00f5es para o melhor funcionamento e organiza\u00e7\u00e3o do evento, que acontece semanalmente \u00e0s quartas-feiras e s\u00e1bados, no Espa\u00e7o das Feiras, o encontro teve como pauta o novo regimento interno da feira.<\/p>\n<p>Presente na abertura dos trabalhos, o prefeito Rodolfo Mota falou sobre a import\u00e2ncia da fam\u00edlia rural para a administra\u00e7\u00e3o municipal e que o objetivo da proposta \u00e9 fortalecer a atividade dos feirantes, garantindo mais transpar\u00eancia nas regras de funcionamento, melhorar a estrutura de atendimento ao p\u00fablico e valorizar a agricultura familiar de Apucarana. Segundo ele, organizar \u00e9 uma forma de cuidar das pessoas e criar condi\u00e7\u00f5es para que os feirantes tenham melhores resultados. \u201cVoc\u00eas, da feira, representam a nossa agricultura familiar, que tem papel estrat\u00e9gico na economia de Apucarana, principalmente pela diversifica\u00e7\u00e3o da produ\u00e7\u00e3o, agrega\u00e7\u00e3o de valor e incentivo \u00e0 perman\u00eancia das fam\u00edlias no campo. At\u00e9 hoje, a feira se manteve pela tradi\u00e7\u00e3o e pelo esfor\u00e7o de cada feirante. Essa atua\u00e7\u00e3o fica agora mais fortalecida com um regimento atualizado\u201d, acentuou Rodolfo Mota.<\/p>\n<p>Durante o encontro, o prefeito apresentou a\u00e7\u00f5es desenvolvidas pela administra\u00e7\u00e3o municipal no meio rural, como a recupera\u00e7\u00e3o de estradas, amplia\u00e7\u00e3o da distribui\u00e7\u00e3o subsidiada de mudas de caf\u00e9, fortalecimento da assist\u00eancia t\u00e9cnica aos produtores e a implanta\u00e7\u00e3o de um novo programa de subs\u00eddio para fertilizantes e adubos. J\u00e1 os feirantes apresentaram demandas relacionadas \u00e0 estrutura da feira, melhorias de acesso, internet, energia el\u00e9trica e conserva\u00e7\u00e3o dos equipamentos utilizados no espa\u00e7o.<\/p>\n<p>O engenheiro agr\u00f4nomo da Secretaria Municipal da Agricultura, Andr\u00e9 Maller, explicou que a Feira do Produtor Rural j\u00e1 possu\u00eda um regimento interno, por\u00e9m o documento estava vinculado apenas \u00e0 Associa\u00e7\u00e3o dos Agropecuaristas Familiares de Apucarana, atualmente conhecida como Associa\u00e7\u00e3o dos Feirantes. Segundo ele, o regulamento foi criado ainda na \u00e9poca em que a feira funcionava no terminal urbano, com apoio t\u00e9cnico da antiga Emater, atual Instituto de Desenvolvimento Rural do Paran\u00e1 (IDR-PR). \u201cCom o passar dos anos, conforme a Emater deixou de atuar diretamente na organiza\u00e7\u00e3o do espa\u00e7o, a feira acabou ficando sem um direcionamento formal por parte do poder p\u00fablico. Como eles ocupam um pr\u00e9dio municipal, que \u00e9 o Espa\u00e7o das Feiras, nada mais adequado do que a prefeitura estabelecer as regras e zelar pelo cumprimento delas\u201d, afirmou Maller.<\/p>\n<p>&#8220;O novo regimento foi elaborado de forma participativa, ouvindo representantes da associa\u00e7\u00e3o, produtores e integrantes do Conselho Municipal de Desenvolvimento Rural. \u201cEste encontro teve objetivo apresentar aos feirantes os direitos e deveres previstos no novo regulamento, al\u00e9m de abrir espa\u00e7o para sugest\u00f5es e ajustes antes da vers\u00e3o definitiva ser encaminhada para an\u00e1lise jur\u00eddica e assinatura do prefeito\u201d, disse o engenheiro agr\u00f4nomo.<\/p>\n<p>Entre os principais pontos previstos no regimento est\u00e3o o que pode ser comercializado, as regras para ocupa\u00e7\u00e3o e sucess\u00e3o das bancas, priorizando produtores rurais de Apucarana com cadastro ativo de produtor rural (CAD\/PRO). Atualmente, a feira conta com cerca de 70 feirantes cadastrados e acontece semanalmente \u00e0s quartas-feiras e s\u00e1bados no Espa\u00e7o das Feiras. \u201cO novo modelo de regimento tamb\u00e9m busca tornar os processos mais t\u00e9cnicos e impessoais, deixando decis\u00f5es ligadas \u00e0 feira sob responsabilidade do Conselho Municipal de Desenvolvimento Rural, formado por representantes de diversas entidades ligadas ao setor agr\u00edcola\u201d, finalizou Maller.<\/p>\n<p>O secret\u00e1rio municipal da Agricultura, Wendel Metta, refor\u00e7ou que o encontro teve car\u00e1ter t\u00e9cnico e organizacional, buscando alinhar procedimentos, atualizar orienta\u00e7\u00f5es e construir de forma participativa o novo regimento interno da Feira do Produtor Rural. \u201cA ideia \u00e9 valorizar cada vez mais o agricultor. Para incentivar e apoiar mais o produtor rural, precisamos come\u00e7ar pela organiza\u00e7\u00e3o, criando regras claras e um ambiente mais estruturado. A partir de agora, tudo passar\u00e1 a ser documentado por meio de protocolo. Isso garante transpar\u00eancia e organiza\u00e7\u00e3o\u201d, assinalou.<\/p>\n<p>Na sua avalia\u00e7\u00e3o, o novo modelo fortalece a gest\u00e3o da feira e d\u00e1 mais seguran\u00e7a aos produtores rurais. \u201cAo longo dos anos, muitas situa\u00e7\u00f5es acabavam sem defini\u00e7\u00e3o clara, j\u00e1 que a associa\u00e7\u00e3o dos feirantes n\u00e3o tinha autonomia para conduzir determinadas decis\u00f5es e a participa\u00e7\u00e3o do poder p\u00fablico era limitada\u201d, explicou Metta. Ele enalteceu a import\u00e2ncia da participa\u00e7\u00e3o do Conselho Municipal de Desenvolvimento Rural na elabora\u00e7\u00e3o e aprova\u00e7\u00e3o das regras. \u201cO texto deste novo regimento foi debatido e aprovado pelos integrantes do conselho, garantindo ampla participa\u00e7\u00e3o das entidades ligadas ao setor agr\u00edcola\u201d, concluiu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agricultores familiares que integram a tradicional Feira do Produtor Rural de Apucarana participaram nesta segunda-feira (25\/05), no sal&atilde;o nobre da prefeitura, de uma reuni&atilde;o com t&eacute;cnicos da Secretaria Municipal da Agricultura. Al&eacute;m do repasse de informa&ccedil;&otilde;es para o melhor funcionamento e organiza&ccedil;&atilde;o do evento, que acontece semanalmente &agrave;s quartas-feiras e s&aacute;bados, no Espa&ccedil;o das Feiras, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":127254,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-127249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/127249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=127249"}],"version-history":[{"count":5,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/127249\/revisions"}],"predecessor-version":[{"id":127273,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/127249\/revisions\/127273"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media\/127254"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=127249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=127249"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=127249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}