{"id":110270,"date":"2025-02-13T17:42:00","date_gmt":"2025-02-13T20:42:00","guid":{"rendered":"https:\/\/www.apucarana.pr.gov.br\/site\/?p=110270"},"modified":"2025-02-13T17:42:00","modified_gmt":"2025-02-13T20:42:00","slug":"apucarana-segue-com-trabalho-emergencial-na-rua-emiliano-perneta","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/site\/apucarana-segue-com-trabalho-emergencial-na-rua-emiliano-perneta\/","title":{"rendered":"Apucarana segue com trabalho emergencial na Rua Emiliano Perneta"},"content":{"rendered":"\n\t\t<!-- MasterSlider -->\n\t\t<div id=\"P_MS6a045bc28d31b\" class=\"master-slider-parent master-slider-gallery   ms-parent-id-0\" style=\"\" >\n\n\t\t\t\n\t\t\t<!-- MasterSlider Main -->\n\t\t\t<div id=\"MS6a045bc28d31b\" class=\"master-slider ms-skin-default\" >\n\t\t\t\t \t\t\t\t \n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"Emiliano Perneta02\" title=\"Emiliano Perneta02\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Emiliano-Perneta02-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Emiliano-Perneta02-1024x683.jpg\" target=\"_self\"    >Emiliano Perneta02<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Emiliano-Perneta02-1024x683-140x80.jpg\" alt=\"Emiliano Perneta02\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"Emiliano Perneta03\" title=\"Emiliano Perneta03\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Emiliano-Perneta03-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Emiliano-Perneta03-1024x683.jpg\" target=\"_self\"    >Emiliano Perneta03<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Emiliano-Perneta03-1024x683-140x80.jpg\" alt=\"Emiliano Perneta03\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"Emiliano Perneta04\" title=\"Emiliano Perneta04\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Emiliano-Perneta04-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Emiliano-Perneta04-1024x683.jpg\" target=\"_self\"    >Emiliano Perneta04<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Emiliano-Perneta04-1024x683-140x80.jpg\" alt=\"Emiliano Perneta04\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"Obras Clot\u00e1rio Portugual01\" title=\"Obras Clot\u00e1rio Portugual01\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Obras-Clotario-Portugual01-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Obras-Clotario-Portugual01-1024x683.jpg\" target=\"_self\"    >Obras Clot\u00e1rio Portugual01<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Obras-Clotario-Portugual01-1024x683-140x80.jpg\" alt=\"Obras Clot\u00e1rio Portugual01\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"Obras Clot\u00e1rio Portugual03\" title=\"Obras Clot\u00e1rio Portugual03\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Obras-Clotario-Portugual03-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Obras-Clotario-Portugual03-1024x683.jpg\" target=\"_self\"    >Obras Clot\u00e1rio Portugual03<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Obras-Clotario-Portugual03-1024x683-140x80.jpg\" alt=\"Obras Clot\u00e1rio Portugual03\" \/>\n\t\t\t\t<\/div>\n\t\t\t<div  class=\"ms-slide\" data-delay=\"3\"    >\n\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/plugins\/masterslider\/public\/assets\/css\/blank.gif\" alt=\"Obras Clot\u00e1rio Portugual04\" title=\"Obras Clot\u00e1rio Portugual04\" data-src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Obras-Clotario-Portugual04-1024x683.jpg\" \/>\n\t<a href=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Obras-Clotario-Portugual04-1024x683.jpg\" target=\"_self\"    >Obras Clot\u00e1rio Portugual04<\/a>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"http:\/\/www.apucarana.pr.gov.br\/site\/wp-content\/uploads\/2025\/02\/Obras-Clotario-Portugual04-1024x683-140x80.jpg\" alt=\"Obras Clot\u00e1rio Portugual04\" \/>\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t<!-- END MasterSlider Main -->\n\n\t\t\t \n\t\t<\/div>\n\t\t<!-- END MasterSlider -->\n\n\t\t<script>\n\t\t( window.MSReady = window.MSReady || [] ).push( function( $ ) {\n\n\t\t\t\"use strict\";\n\t\t\tvar masterslider_d31b = new MasterSlider();\n\n\t\t\t\/\/ slider controls\n\t\t\tmasterslider_d31b.control('arrows'     ,{ autohide:true, overVideo:true  });\n\t\t\tmasterslider_d31b.control('thumblist'  ,{ autohide:false, overVideo:true, dir:'h', speed:17, inset:false, arrows:false, hover:false, customClass:'', align:'bottom',type:'thumbs', margin:2, width:140, height:80, space:2, fillMode:'fill'  });\n\t\t\t\/\/ slider setup\n\t\t\tmasterslider_d31b.setup(\"MS6a045bc28d31b\", {\n\t\t\t\twidth           : 960,\n\t\t\t\theight          : 540,\n\t\t\t\tminHeight       : 0,\n\t\t\t\tspace           : 0,\n\t\t\t\tstart           : 1,\n\t\t\t\tgrabCursor      : true,\n\t\t\t\tswipe           : true,\n\t\t\t\tmouse           : true,\n\t\t\t\tkeyboard        : false,\n\t\t\t\tlayout          : \"fillwidth\",\n\t\t\t\twheel           : false,\n\t\t\t\tautoplay        : true,\n                instantStartLayers:false,\n\t\t\t\tmobileBGVideo:false,\n\t\t\t\tloop            : true,\n\t\t\t\tshuffle         : false,\n\t\t\t\tpreload         : 3,\n\t\t\t\theightLimit     : false,\n\t\t\t\tautoHeight      : false,\n\t\t\t\tsmoothHeight    : true,\n\t\t\t\tendPause        : false,\n\t\t\t\toverPause       : false,\n\t\t\t\tfillMode        : \"fill\",\n\t\t\t\tcenterControls  : true,\n\t\t\t\tstartOnAppear   : false,\n\t\t\t\tlayersMode      : \"center\",\n\t\t\t\tautofillTarget  : \"\",\n\t\t\t\thideLayers      : false,\n\t\t\t\tfullscreenMargin: 0,\n\t\t\t\tspeed           : 17,\n\t\t\t\tdir             : \"h\",\n\t\t\t\tresponsive      : true,\n\t\t\t\ttabletWidth     : 768,\n\t\t\t\ttabletHeight    : null,\n\t\t\t\tphoneWidth      : 480,\n\t\t\t\tphoneHeight    : null,\n\t\t\t\tsizingReference : window,\n\t\t\t\tparallaxMode    : 'swipe',\n\t\t\t\tview            : \"basic\"\n\t\t\t});\n\n\t\t\t\n\t\t\twindow.masterslider_instances = window.masterslider_instances || [];\n\t\t\twindow.masterslider_instances.push( masterslider_d31b );\n\t\t});\n\t\t<\/script>\n\n\n<p>A Secretaria de Obras da Prefeitura de Apucarana atua em car\u00e1ter emergencial com equipe pr\u00f3pria, na recupera\u00e7\u00e3o de um trecho da Rua Emiliano Perneta, no Jardim Ponta Grossa, pr\u00f3ximo ao entroncamento com a Rua Piratininga, mas imedia\u00e7\u00f5es do p\u00e1tio de m\u00e1quinas da prefeitura.<\/p>\n<p>Segundo assinala o prefeito Rodolfo Mota o trabalho visa garantir seguran\u00e7a e o m\u00ednimo de trafegabilidade no trecho at\u00e9 a conclus\u00e3o do processo licitat\u00f3rio de contrata\u00e7\u00e3o de empresa para dar solu\u00e7\u00e3o efetiva ao problema. Mota lembra que a galeria pluvial e o pavimento asf\u00e1ltico sofreram danos significativos ap\u00f3s temporal registrado no in\u00edcio do m\u00eas de dezembro do ano passado. \u201cNa ocasi\u00e3o, a chuva foi intensa e se concentrou em um curto espa\u00e7o de tempo com registro de cerca de 35 mil\u00edmetros em cerca de uma hora. O problema foi agravado no \u00faltimo dia 16 de janeiro, a partir da ocorr\u00eancia de mais uma forte chuva\u201d, relata o prefeito Rodolfo Mota.<\/p>\n<p>De acordo com o secret\u00e1rio Municipal de Obras, engenheiro civil Mateus Franciscon Fernandes, o problema teve origem a partir do rompimento da galeria pluvial, que n\u00e3o suportou a quantidade de \u00e1gua. \u201cEstamos agora realizando uma interven\u00e7\u00e3o emergencial provis\u00f3ria at\u00e9 a licita\u00e7\u00e3o ser conclu\u00edda, com a abertura de duas valetas que v\u00e3o direcionar a \u00e1gua da chuva para que ela n\u00e3o escoe pelo pavimento\u201d, explica Fernandes, frisando que a prefeitura tamb\u00e9m realiza a limpeza de todas as bocas de lobo na regi\u00e3o. \u201cAl\u00e9m disto, atuamos na manuten\u00e7\u00e3o de um dissipador que estava assoreado. Em uma for\u00e7a-tarefa at\u00e9 a contrata\u00e7\u00e3o de uma empresa especializada respons\u00e1vel pela reconstru\u00e7\u00e3o definitiva do trecho, envolvendo galerias pluviais, bocas de lobo, meio-fio e pavimenta\u00e7\u00e3o asf\u00e1ltica\u201d, esclarece o secret\u00e1rio de Obras. O investimento previsto para a licita\u00e7\u00e3o \u00e9 na ordem de R$300 mil.<\/p>\n<p><strong>Clot\u00e1rio Portugal<\/strong> \u2013 Ainda no setor de pavimenta\u00e7\u00e3o, o secret\u00e1rio Mateus Franciscon Fernandes informou que a prefeitura finalizou nesta semana a recupera\u00e7\u00e3o do sistema de drenagem e recomposi\u00e7\u00e3o do asfalto em trecho da Rua Desembargador Clot\u00e1rio Portugal. \u201cO problema teve origem com o rompimento da tubula\u00e7\u00e3o devido a a\u00e7\u00e3o das \u00e1guas da chuva, resultando em uma grande cratera em um ponto entre os cruzamentos com as ruas Guarapuava e S\u00e3o Jer\u00f4nimo. Com isso, parte da pista de rolagem precisou ser interditada para a execu\u00e7\u00e3o da obra\u201d, contextualiza o secret\u00e1rio, ressaltando que com a conclus\u00e3o dos servi\u00e7os, \u201co tr\u00e1fego de ve\u00edculos est\u00e1 agora liberado nas duas pistas\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Obras da Prefeitura de Apucarana atua em car&aacute;ter emergencial com equipe pr&oacute;pria, na recupera&ccedil;&atilde;o de um trecho da Rua Emiliano Perneta, no Jardim Ponta Grossa, pr&oacute;ximo ao entroncamento com a Rua Piratininga, mas imedia&ccedil;&otilde;es do p&aacute;tio de m&aacute;quinas da prefeitura. Segundo assinala o prefeito Rodolfo Mota o trabalho visa garantir seguran&ccedil;a e [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":110289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-110270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/110270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/comments?post=110270"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/110270\/revisions"}],"predecessor-version":[{"id":110294,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/posts\/110270\/revisions\/110294"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media\/110289"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/media?parent=110270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/categories?post=110270"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/site\/wp-json\/wp\/v2\/tags?post=110270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}