{"id":6846,"date":"2018-02-06T15:17:02","date_gmt":"2018-02-06T17:17:02","guid":{"rendered":"http:\/\/www.apucarana.pr.gov.br\/ame\/?p=6846"},"modified":"2024-10-08T09:10:12","modified_gmt":"2024-10-08T12:10:12","slug":"convocados-em-concurso-publico-se-apresentam-para-suprir-vagas","status":"publish","type":"post","link":"http:\/\/www.apucarana.pr.gov.br\/ame\/convocados-em-concurso-publico-se-apresentam-para-suprir-vagas\/","title":{"rendered":"Convocados em concurso p\u00fablico se apresentam para suprir vagas"},"content":{"rendered":"<p>A Autarquia Municipal de Educa\u00e7\u00e3o apresentou, na manh\u00e3 desta ter\u00e7a-feira (06\/02), 30 convocados no concurso p\u00fablico n\u00ba 023\/2016. A cerim\u00f4nia ocorreu no sal\u00e3o nobre da Prefeitura de Apucarana, onde eles foram recebidos pelo prefeito em exerc\u00edcio, J\u00fanior da Femac.<\/p>\n<p>A rede municipal de ensino disp\u00f5e atualmente de 60 estabelecimentos, entre Escolas e CMEIs, que demandam n\u00e3o apenas de estrutura f\u00edsica adequada, mas tamb\u00e9m de profissionais qualificados para atender aos mais de dez mil alunos.<\/p>\n<p>\u201cOs convocados nesse momento s\u00e3o para o cargo de auxiliar de servi\u00e7os gerais. Eles devem substituir alguns dos nossos servidores que entraram com pedido de aposentadoria ou de exonera\u00e7\u00e3o,\u201d explicou a secret\u00e1ria municipal de educa\u00e7\u00e3o, Marli Fernandes.<\/p>\n<p>O prefeito em exerc\u00edcio, J\u00fanior da Femac, parabenizou os profissionais que se apresentaram com o interesse de ingressar no quadro de funcion\u00e1rios da Autarquia Municipal de Educa\u00e7\u00e3o. \u00a0\u201cA gest\u00e3o do prefeito Beto Preto tem o compromisso de ofertar ensino de qualidade nas nossas 37 Escolas e 23 CMEIs. Eu pe\u00e7o que voc\u00eas tamb\u00e9m abracem essa causa e deem o melhor de si na fun\u00e7\u00e3o que est\u00e3o assumindo. Afinal, voc\u00eas estar\u00e3o lidando diariamente com o nosso bem mais importante: as crian\u00e7as apucaranenses,\u201d disse.<\/p>\n<p>Nos pr\u00f3ximos dias, os convocados ainda v\u00e3o realizar o exame m\u00e9dico admissional e entregar a documenta\u00e7\u00e3o exigida pela Superintend\u00eancia de Recursos Humanos. Eles devem ir para as Escolas e CMEIs no in\u00edcio de mar\u00e7o.<\/p>\n<div class = 'socialMediaOnEveryPost'>Compartilhe<div id=\"sgmbShare1-1\" class=\"sgmbShare jssocials-theme-classic sgmbWidget1-1\"><\/div><div class=\"dropdownWrapper dropdownWrapper1 dropdownWrapper-for-widget \" id=\"dropdownWrapper-for-widget\">\r\n\t\t\t\t\t\t<div class=\"dropdownLabel\" id=\"dropdownLabel-share-list\"><span class=\"sgmbButtonListLabel1\">Share List<\/span><\/div>\r\n\t\t\t\t\t\t<div class=\"dropdownPanel dropdownPanel1-1\">\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div><script>  SGMB_URL = \"http:\/\/www.apucarana.pr.gov.br\/ame\/wp-content\/plugins\/social-media-builder\/\"; jQuery(\".dropdownWrapper\").hide(); SGMB_GOOGLE_ACOUNT = \"\"; <\/script><script type=\"text\/javascript\">\r\n\t\tjQuery(document).ready(function($){var widget = new SGMBWidget();widget.show({\"id\":\"1\",\"title\":\"Face\\\/Twitter\",\"options\":{\"currentUrl\":\"1\",\"url\":\"\",\"shareText\":\"\",\"fontSize\":\"14\",\"betweenButtons\":\"1px\",\"theme\":\"classic\",\"sgmbButtonsPosition\":\"bottomLeft\",\"socialTheme\":\"\",\"icon\":\"default\",\"buttonsPanelEffect\":\"No Effect\",\"buttonsEffect\":\"No Effect\",\"iconsEffect\":\"No Effect\",\"buttons\":\"{\\\"facebook\\\":{\\\"label\\\":\\\"Share\\\",\\\"icon\\\":\\\"default-facebook\\\"},\\\"twitter\\\":{\\\"label\\\":\\\"Tweet\\\",\\\"icon\\\":\\\"default-twitter\\\",\\\"via\\\":\\\"\\\",\\\"hashtags\\\":\\\"\\\"}}\",\"roundButton\":\"\",\"showLabels\":\"\",\"showCounts\":\"\",\"showCenter\":\"\",\"showButtonsAsList\":\"\",\"sgmbDropdownColor\":\"\",\"sgmbDropdownLabelFontSize\":\"14\",\"sgmbDropdownLabelColor\":\"\",\"showButtonsOnEveryPost\":\"on\",\"selectedOrExcluded\":\"\",\"showButtonsOnEveryPage\":\"\",\"textOnEveryPost\":\"Compartilhe\",\"showButtonsOnCustomPost\":\"\",\"textOnCustomPost\":\"\",\"showButtonsOnMobileDirect\":\"on\",\"showButtonsOnDesktopDirect\":\"on\",\"sgmbSelectedPages\":[\"\"],\"sgmbExcludedPosts\":[\"\"],\"sgmbSelectedCustomPosts\":[],\"showButtonsInPopup\":\"\",\"titleOfPopup\":\"\",\"descriptionOfPopup\":\"\",\"showPopupOnLoad\":\"\",\"showPopupOnScroll\":\"\",\"showPopupOnExit\":\"\",\"openSecondsOfPopup\":\"\",\"googleAnaliticsAccount\":\"\"},\"buttonOptions\":{\"facebook\":{\"label\":\"Share\",\"icon\":\"default-facebook\"},\"twitter\":{\"label\":\"Tweet\",\"icon\":\"default-twitter\",\"via\":\"\",\"hashtags\":\"\"}},\"button\":[\"facebook\",\"twitter\"]}, 1, '', 'http:\/\/www.apucarana.pr.gov.br\/ame\/wp-content\/uploads\/2018\/02\/SERVIDORESPROFETA-2.jpg', '', 'http:\/\/www.apucarana.pr.gov.br\/ame\/convocados-em-concurso-publico-se-apresentam-para-suprir-vagas\/'); });<\/script><\/div><script> jQuery(\".socialMediaOnEveryPost\").addClass(\"sgmb-left\") <\/script>","protected":false},"excerpt":{"rendered":"<p>Os 30 chamados nesse momento s\u00e3o para o cargo de auxiliar de servi\u00e7os gerais. Eles devem substituir servidores das Escolas e CMEIs que se aposentaram ou pediram exonera\u00e7\u00e3o recentemente (Fotos: Profeta)<\/p>\n","protected":false},"author":10,"featured_media":6847,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"http:\/\/www.apucarana.pr.gov.br\/ame\/wp-json\/wp\/v2\/posts\/6846"}],"collection":[{"href":"http:\/\/www.apucarana.pr.gov.br\/ame\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.apucarana.pr.gov.br\/ame\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/ame\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/ame\/wp-json\/wp\/v2\/comments?post=6846"}],"version-history":[{"count":1,"href":"http:\/\/www.apucarana.pr.gov.br\/ame\/wp-json\/wp\/v2\/posts\/6846\/revisions"}],"predecessor-version":[{"id":6851,"href":"http:\/\/www.apucarana.pr.gov.br\/ame\/wp-json\/wp\/v2\/posts\/6846\/revisions\/6851"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/ame\/wp-json\/wp\/v2\/media\/6847"}],"wp:attachment":[{"href":"http:\/\/www.apucarana.pr.gov.br\/ame\/wp-json\/wp\/v2\/media?parent=6846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/ame\/wp-json\/wp\/v2\/categories?post=6846"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.apucarana.pr.gov.br\/ame\/wp-json\/wp\/v2\/tags?post=6846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}